{"id":17196,"date":"2022-10-13T12:43:30","date_gmt":"2022-10-13T12:43:30","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=17196"},"modified":"2022-10-13T12:43:31","modified_gmt":"2022-10-13T12:43:31","slug":"year-5-science-fair-for-year-5-parents","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/year-5-science-fair-for-year-5-parents\/","title":{"rendered":"Year 5 Science Fair per i genitori Year 5"},"content":{"rendered":"<p>siamo felici di invitare tutti i <strong>genitori Year 5 <\/strong>a partecipare alla primissima Year 5 Science Fair.<\/p>\n\n\n\n<p>L'evento si svolger\u00e0 venerd\u00ec 21 ottobre dalle 14:00 alle 15:00 nelle aule Y5, nel Campo e nell'Outlook nell\u2019edificio PYP. Vi invitiamo a venire e a parlare con vostro figlio e i suoi compagni di classe di ci\u00f2 che stanno imparando. Alcune delle esposizioni saranno interattive e gli studenti condivideranno la loro conoscenza del processo scientifico.<\/p>\n\n\n\n<p>Non vediamo l'ora di accogliere il maggior numero possibile di <strong>genitori Year 5<\/strong> genitori di Year 5. Per aiutarci a organizzare al meglio lo spazio, per favore RSVP (registrati) su <a href=\"https:\/\/docs.google.com\/document\/d\/1PPxlKxJ9ZU4GwwDRLccIXz3TLX30QgAGG8a3Nte6TYQ\/edit\" target=\"_blank\" rel=\"noopener\">questo documento condiviso.<\/a><\/p>\n\n\n\n<p>Per gli studenti i cui genitori non possono partecipare, organizzeremo la visita da parte di studenti di altre classi, in modo da permettere loro di presentare il loro apprendimento.<\/p>","protected":false},"excerpt":{"rendered":"<p>We are delighted to be able to invite all Year 5 parents to come and participate in the very first Year 5 Science Fair. The event will take place on Friday the 21st October from 14:00 until 15:00 in the Y5 classrooms, the Campo and the Outlook. Please come and talk to your child and [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,58],"tags":[130,182,197],"week":[195],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/IMG_1747-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17196"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=17196"}],"version-history":[{"count":1,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17196\/revisions"}],"predecessor-version":[{"id":17198,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17196\/revisions\/17198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/17201"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=17196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=17196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=17196"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=17196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}