{"id":17220,"date":"2022-10-13T12:43:10","date_gmt":"2022-10-13T12:43:10","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=17220"},"modified":"2022-10-13T12:43:11","modified_gmt":"2022-10-13T12:43:11","slug":"halloween-event-for-pyp-students","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/halloween-event-for-pyp-students\/","title":{"rendered":"Evento di Halloween per studenti PYP"},"content":{"rendered":"<p>Vi preghiamo di leggere il messaggio qui di seguito da parte di un fantastico team di studenti DP (High School) che stanno organizzando un divertente evento di Halloween per i nostri studenti PYP. Nota: questo evento si svolger\u00e0 al termine della giornata scolastica dalle 13:30 alle 15:15 del 27 ottobre, ultimo giorno prima della pausa di met\u00e0 semestre. Questo evento <strong>\u00e8 riservato ai nostri studenti.<\/strong><\/p>\n\n\n\n<p>Gli studenti PYP possono portare i costumi di Halloween a scuola quel giorno e indossarli prima che il DP Halloween Train inizi nel pomeriggio. Gli studenti non dovrebbero venire a scuola gi\u00e0 vestiti con i loro costumi di Halloween. Ricordate che abbiamo bambini molto piccoli nella scuola, quindi assicuratevi che il costume di Halloween di vostro figlio <strong>non includa armi<\/strong> e che <strong>non spaventi i nostri bambini pi\u00f9 piccoli.<\/strong>Vi preghiamo anche di non permettere a vostro figlio di portare del sangue finto. Il vostro bambino dovrebbe essere in grado di indossare autonomamente il proprio costume di Halloween con un minimo aiuto da parte degli insegnanti.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><em>Salve genitori PYP,<\/em><\/p>\n\n\n\n<p><em>Siamo entusiasti di dirvi che quest'anno vogliamo festeggiare Halloween con i vostri bambini!<\/em><\/p>\n\n\n\n<p><em>Noi DP1 stiamo creando un Trail di Halloween per tutti i PYP, che consiste nel vestirsi come i vostri personaggi preferiti o nell'incontrarli, nel fare giochi che vanno dalla caccia al tesoro al lancio della zucca e nel mangiare caramelle di Halloween.<\/em><\/p>\n\n\n\n<p><em>Non lo facciamo solo per Halloween, ma anche per raccogliere fondi per l'UNICEF. Una donazione a partire da 5 euro sarebbe estremamente apprezzata, in modo da avere il massimo impatto possibile. Tutti i fondi saranno destinati a un trattamento per la malnutrizione grave, il RUTF.<\/em><\/p>\n\n\n\n<p><em>Abbiamo anche bisogno di aiuto con del materiale riciclato. Abbiamo creato un poster nella speranza di ottenere un ulteriore aiuto da parte vostra, chiedendovi di donare i materiali elencati qui di seguito: <\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"332\" src=\"http:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Recycling-Poster.png\" alt=\"\" class=\"wp-image-17222\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Recycling-Poster.png 1528w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Recycling-Poster-300x97.png 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Recycling-Poster-1024x332.png 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Recycling-Poster-768x249.png 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Recycling-Poster-18x6.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em>Potete consegnarli nell'edificio PYP prima del 26 ottobre.<\/em><\/p>\n\n\n\n<p><em>Ci auguriamo che questa iniziativa sia altrettanto emozionante per i vostri bambini di quanto lo \u00e8 per noi.<\/em><\/p>\n\n\n\n<p><em>Non vediamo l'ora di vedere tutti i PYP divertirsi!<br>Emma D'Andria, Chiara Zanatta, Letizia Possamai<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"690\" height=\"974\" src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Event-Poster.png\" alt=\"\" class=\"wp-image-17223\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Event-Poster.png 690w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Event-Poster-213x300.png 213w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Event-Poster-9x12.png 9w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Please read the message below from a fantastic team of DP (High School) students who are organizing a fun Halloween event for our PYP students. Note: this event will take place at the end of the school day from 13:30-15:15 on October 27th, the last day before the half term break. This is an event [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17226,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58,1],"tags":[17,199,200,198,201],"week":[195],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/10\/Screenshot-2022-10-13-at-13.58.07.png","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17220"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=17220"}],"version-history":[{"count":6,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17220\/revisions"}],"predecessor-version":[{"id":17229,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17220\/revisions\/17229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/17226"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=17220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=17220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=17220"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=17220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}