{"id":17537,"date":"2022-11-16T09:48:15","date_gmt":"2022-11-16T09:48:15","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=17537"},"modified":"2022-11-17T14:46:57","modified_gmt":"2022-11-17T14:46:57","slug":"reminders-pyp-update-17-11-22","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/reminders-pyp-update-17-11-22\/","title":{"rendered":"Promemoria PYP - aggiornamento 17.11.22"},"content":{"rendered":"<p><strong>Fiera\/Vendita di libri in inglese - gioved\u00ec 24 novembre - 10:00-16:30<\/strong><br>Gioved\u00ec 24 novembre ospiteremo una fiera\/vendita di libri per tutta la giornata. Tutti gli studenti visiteranno la fiera\/vendita durante la giornata scolastica e i genitori sono invitati a visitarla dalle 15:30 alle 16:30. \u00c8 una grande opportunit\u00e0 per acquistare libri in inglese per i regali di Natale per vostro figlio. Tutti i libri costano, in media, 8-9 euro. Tuo figlio dovrebbe portare i soldi in una busta sigillata, etichettata con il suo nome. Non vediamo l'ora di mettere ancora pi\u00f9 libri nelle mani dei nostri studenti!!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>Workshop per genitori: pre-adolescenza - con Rocio Ortega - 1 dicembre ore 9:00 in Outlook PYP<\/strong><br>Questa sessione \u00e8 adatta per i genitori Y4 e Y5 che desiderano saperne di pi\u00f9 sui cambiamenti che fanno parte della pre-adolescenza e su come i genitori possono sostenere il loro bambino durante questa importante fase. Se non potete partecipare di persona a questa sessione, unitevi a noi online utilizzando questo link: <a href=\"https:\/\/h-farm.webex.com\/meet\/jane.andrews\" target=\"_blank\" rel=\"noopener\">https:\/\/h-farm.webex.com\/meet\/jane.andrews<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>Y5 - visita didattica al Museo Archeologico di Altino - luned\u00ec 21 novembre<\/strong><br>Vi ricordiamo di leggere a <a href=\"https:\/\/drive.google.com\/file\/d\/1HlbDCs_6-uZFIb6700Lq-0q1ivvJX1Qk\/view\" target=\"_blank\" rel=\"noopener\">questo link<\/a> la lettera delle insegnanti di classe sulla prossimo visita didattica.<\/p>\n\n\n\n<p><strong>Y4 - visita didattica al Guggenheim - venerd\u00ec 25 novembre<\/strong><br>Vi ricordiamo di leggere a <a href=\"https:\/\/drive.google.com\/file\/d\/1sM1uPB3qdG1sc5aLAurHsX6u8zdwvYwF\/view\" target=\"_blank\" rel=\"noopener\">questo link<\/a> la lettera delle insegnanti di classe sulla prossimo visita didattica.<\/p>\n\n\n\n<p><strong>Y5 - visita didattica a Verona - venerd\u00ec 2 dicembre<\/strong><br>Vi ricordiamo di leggere a <a href=\"https:\/\/drive.google.com\/file\/d\/1CJMuEhXP7fJbgusLW4vw2yRss7so7zNJ\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\">questo link<\/a> la lettera delle insegnanti di classe sulla prossimo visita didattica.<\/p>","protected":false},"excerpt":{"rendered":"<p>English Book Fair\/Sale &#8211; Thursday, November 24 &#8211; 10:00-16:30We will host a book fair\/sale throughout the day on Thursday, November 24th. All students will visit the fair\/sale during the school day and parents are invited in from 15:30-16:30. This is a great opportunity to purchase books in English for Christmas presents for your child. All [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58],"tags":[17,130,141,209],"week":[260],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/11\/HIS_2022_06_15_EYUlife_12_social.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17537"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=17537"}],"version-history":[{"count":1,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17537\/revisions"}],"predecessor-version":[{"id":17538,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17537\/revisions\/17538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/17485"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=17537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=17537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=17537"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=17537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}