{"id":17884,"date":"2022-12-07T15:37:01","date_gmt":"2022-12-07T15:37:01","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=17884"},"modified":"2022-12-07T15:40:56","modified_gmt":"2022-12-07T15:40:56","slug":"pyp-dismissal-procedures-for-the-pta-party-on-friday-december-16","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/pyp-dismissal-procedures-for-the-pta-party-on-friday-december-16\/","title":{"rendered":"Procedure di uscita studenti PYP per il PTA Party di venerd\u00ec 16 dicembre"},"content":{"rendered":"<p>Il PTA Winter Fair \u00e8 un <strong>evento per famiglie <\/strong>e gli studenti PYP parteciperanno con i loro genitori e non come gruppi di classe. Gli studenti possono indossare un <strong>maglione natalizio<\/strong> a scuola venerd\u00ec 16 dicembre se lo desiderano.<\/p>\n\n\n\n<p>Venerd\u00ec 16 dicembre gli studenti PYP potranno:<\/p>\n\n\n\n<ul><li>essere presi dai genitori <strong>alle 14:30 (eccezionalmente al cancelletto PYP)<\/strong> per recarsi a The Hill per la festa del PTA<\/li><li>essere presi dai genitori <strong>essere presi dai genitori alle piante del Welcome Center al solito orario di uscita alle 15:15<\/strong> per recarsi a The Hill per la festa del PTA<\/li><li>confermare la loro <strong>attivit\u00e0 sportiva abituale del venerd\u00ec<\/strong> ed essere presi dai genitori alle 16:15 o prendere un bus scolastico delle 16:35<\/li><li>prendere l\u2019abituale <strong>bus scolastico delle 15:30<\/strong> per Treviso<\/li><li>rimanere in supervisione e prendere il solito <strong>bus scolastico che parte alle 16:35<\/strong><\/li><\/ul>\n\n\n\n<p>Per aiutarci con la logistica di questa giornata, vi preghiamo di compilare <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeZ5Z4sMoWorKZmmeHwzyNGIK6IgB1yeaS6CsVjyeE8BN1y0w\/viewform\" target=\"_blank\" rel=\"noopener\">questo form<\/a> per confermare il programma di uscita di vostro figlio.<\/p>\n\n\n\n<p><strong>Tutti i bus scolastici funzioneranno normalmente quel giorno. Solo Vocal Coaching, Graphic Design e il Reading Club EYU saranno eccezionalmente sospesi venerd\u00ec 16.<\/strong><br>Se non prenderete vostro figlio alle 14:30 per partecipare al PTA Winter Party, lui\/lei rimarr\u00e0 a scuola fino alla fine della giornata scolastica (15:15) e la sua uscita sar\u00e0 quella regolare di ogni venerd\u00ec (preso dai genitori, attivit\u00e0 sportiva, bus scolastico o al termine della supervisione, se applicabile).<\/p>\n\n\n\n<p><strong>Solo genitori Y5:<\/strong> vi ricordiamo che il tour dell\u2019edificio MYP\/DP \u00e8 in programma per voi alle 14:00, il punto di ritrovo \u00e8 nell'area reception dell'edificio MYP\/DP. Dopo la visita dovrete andare a prendere i vostri figli nell'edificio PYP, e vi incoraggiamo a godervi tutti insieme la PTA Winter Fair dopo.<\/p>\n\n\n\n<p>Il programma del PTA Winter Party \u00e8 illustrato a seguire:<\/p>\n\n\n\n<figure class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"724\" height=\"1024\" data-id=\"17885\"  src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13-724x1024.jpg\" alt=\"\" class=\"wp-image-17885\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13-724x1024.jpg 724w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13-212x300.jpg 212w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13-768x1086.jpg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13-1086x1536.jpg 1086w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13-8x12.jpg 8w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13.jpg 1240w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"724\" height=\"1024\" data-id=\"17886\"  src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13_2-724x1024.jpg\" alt=\"\" class=\"wp-image-17886\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13_2-724x1024.jpg 724w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13_2-212x300.jpg 212w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13_2-768x1086.jpg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13_2-1086x1536.jpg 1086w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13_2-8x12.jpg 8w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/Winter-Fair-2022-13_2.jpg 1240w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption\"><br><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>The PTA Winter Fair is a family event and PYP students will attend with their parents and not as class groups. Students can wear a Christmas jumper to school on Friday, December 16th if they choose to do so. On Friday, December 16th, PYP students can: be collected by their parents at 14:30 (exceptionally at [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17939,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58],"tags":[305,149,304],"week":[302],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/12\/H-FARM_Spazio_11-14.27.42.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17884"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=17884"}],"version-history":[{"count":6,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17884\/revisions"}],"predecessor-version":[{"id":17940,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/17884\/revisions\/17940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/17939"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=17884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=17884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=17884"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=17884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}