{"id":18220,"date":"2023-01-26T15:11:30","date_gmt":"2023-01-26T15:11:30","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=18220"},"modified":"2023-01-26T15:11:32","modified_gmt":"2023-01-26T15:11:32","slug":"delf-french-exam-preparation-course-for-myp-2-5-2","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/delf-french-exam-preparation-course-for-myp-2-5-2\/","title":{"rendered":"Esame di francese DELF - corso di preparazione per MYP 2-5"},"content":{"rendered":"<p>Gentili famiglie,<\/p>\n\n\n\n<p>Siamo lieti di annunciare che tra febbraio e giugno stiamo organizzando un corso di preparazione al diploma di lingua francese (DELF A1-A2-B1-B2) per i nostri <strong>studenti MYP 2, MYP 3, MYP 4 e MYP 5. <\/strong>Questi certificati linguistici ufficiali sono riconosciuti in tutto il mondo e sono validi per tutta la vita!<\/p>\n\n\n\n<p>Il prezzo del corso \u00e8 di 330 \u20ac per studente, che comprende:<\/p>\n\n\n\n<ul><li>20 lezioni di preparazione al DELF (una volta alla settimana durante la pausa pranzo: 12:45-13:30);<\/li><li>spese di iscrizione alla sessione d'esame DELF di met\u00e0 giugno presso l'Alliance Fran\u00e7aise de Venise;<\/li><li>trasporto all'Alliance Fran\u00e7aise de Venise il giorno dell\u2019esame.<\/li><\/ul>\n\n\n\n<p>Le date d'esame sono le seguenti:&nbsp;&nbsp;<\/p>\n\n\n\n<ul><li>prove di ascolto, lettura e scrittura: A1 - 6 giugno; A2 - 6 giugno; B1 - 7 giugno; B2 - 1 giugno;<\/li><li>orali individuali: A1-A2-B1-B2 - tra il 1\u00b0 e il 30 giugno.<\/li><\/ul>\n\n\n\n<p><strong>Il corso sar\u00e0 tenuto da Mr Robin Anav. Si prega di contattare direttamente Mr Anav all'indirizzo&nbsp;<a href=\"mailto:robin.anav@h-is.com\" target=\"_blank\" rel=\"noreferrer noopener\">robin.anav@h-is.com<\/a>&nbsp;prima dell'iscrizione e del pagamento per garantire una scelta corretta del livello (A1-A2-B1-B2) e verificare la disponibilit\u00e0.<\/strong><\/p>\n\n\n\n<p>Vi chiediamo gentilmente di confermare l'iscrizione dello studente e di effettuare il pagamento entro il 30 gennaio 2023, seguendo queste istruzioni: accedere con il proprio indirizzo e-mail alla piattaforma di iscrizione (<a href=\"https:\/\/www.h-is.com\/application\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.h-is.com\/application\/<\/a>) e aprire la sezione \"Attivit\u00e0 extra\". Selezionando l'anno scolastico 2022-23, troverete il prodotto DELF Preparation Course.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dear Families, We are happy to inform you that between February and June 2023, we are organizing a French language diploma (DELF A1-A2-B1-B2) preparation course for our MYP 2, MYP 3, MYP 4 and MYP 5 students. These official language certificates are recognized worldwide and are valid for a lifetime! The price of the course [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":18061,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[52,53,54,55],"tags":[327,324,326,325],"week":[351],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2023\/01\/anthony-choren-lYzap0eubDY-unsplash-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18220"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=18220"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18220\/revisions"}],"predecessor-version":[{"id":18251,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18220\/revisions\/18251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/18061"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=18220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=18220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=18220"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=18220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}