{"id":18321,"date":"2023-02-02T15:06:04","date_gmt":"2023-02-02T15:06:04","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=18321"},"modified":"2023-02-02T15:06:04","modified_gmt":"2023-02-02T15:06:04","slug":"cas-sa-projects-and-initiatives-6","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/cas-sa-projects-and-initiatives-6\/","title":{"rendered":"Progetti e iniziative CAS\/SA"},"content":{"rendered":"<p>\ud83d\ude4f In preparazione all'evento <a href=\"https:\/\/asalh.org\/black-history-themes\/\" target=\"_blank\" rel=\"noopener\">Mese della consapevolezza della storia afroamericana<\/a> che si terr\u00e0 a Febbraio, i nostri studenti stanno lavorando ad un progetto CAS che presenter\u00e0 i poster di personaggi illustri e le loro conquiste. Leggete il <a href=\"https:\/\/drive.google.com\/file\/d\/1D1DXX0fUgWczUOvlRUvCAhqhDf3h2NKj\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui il poster<\/a> e <a href=\"https:\/\/drive.google.com\/file\/d\/1mdzvXenpQ5RZ_Fz3k11THoMCTl64Zb3a\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">il poster dei personaggi qui<\/a><strong>.<\/strong><\/p>\n\n\n\n<p>\ud83c\udf97\ufe0fCercasi artisti per il prossimo H-Farm Talent Show: per una campagna di raccolta fondi! Ti piace cantare, ballare, fare trucchi di magia, commedie, barzellette, scenette, ginnastica, suonare uno strumento? Ulteriori dettagli e informazioni sulle iscrizioni <a href=\"https:\/\/drive.google.com\/file\/d\/1iiVAn2Q5clK1377nEKBPmlHP98gheowz\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui il poster<\/a>. Contiamo sull'aiuto dei genitori per convincere gli studenti a iscriversi a questo simpatico evento comunitario.<\/p>\n\n\n\n<p>\ud83e\udd58 Ricordate <a href=\"https:\/\/drive.google.com\/file\/d\/1gO91IIBpLFuNwcG26TgXeeU03mLtguaH\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">Foody<\/a>, il progetto di ricettario comunitario di H-FARM, destinato a raccogliere fondi per<a href=\"https:\/\/resq.it\/en\/home-english\/\" target=\"_blank\" rel=\"noreferrer noopener\"> ResQ<\/a>, la flotta civile umanitaria che salva i migranti nel Mediterraneo? Il nostro ricettario Foody \u00e8 disponibile <a href=\"https:\/\/drive.google.com\/file\/d\/1OmTUC8ln8HSHcF9cPRLnfwJELE8U4VVU\/view?usp=share_link\" target=\"_blank\" rel=\"noreferrer noopener\">qui<\/a> e lo stiamo riproponendo alla nostra comunit\u00e0. Vi invitiamo a fare una donazione a favore di <a href=\"https:\/\/resq.it\/en\/home-english\/\">ResQ<\/a>: una cassetta di raccolta \u00e8 disponibile alla reception di MYP\/DP. Il vostro contributo \u00e8 molto apprezzato!<\/p>\n\n\n\n<p>\ud83c\udf97\ufe0fSiamo lieti di condividere il prossimo <a href=\"https:\/\/drive.google.com\/file\/d\/1-CinTgNDKIgfsbFdqRopR9oWtklCdne2\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\">Workshop di alfabetizzazione digitale per gli anziani di Roncade<\/a>, in collaborazione con la Fondazione Citt\u00e0 di Roncade. L'iniziativa mira a creare connessioni intergenerazionali, a colmare il divario digitale, a migliorare l'accesso alle informazioni e ai servizi, a migliorare la socializzazione e il benessere mentale degli anziani, che potranno rimanere in contatto online con le famiglie e gli amici, e a preparare gli anziani per il lavoro e l'economia futuri. Un gruppo di 40 anziani locali sar\u00e0 accolto presso il nostro campus per una serie di 6 incontri il mercoled\u00ec, dalle 16:30 alle 18:00. Ringraziamo i nostri 15 studenti volontari per aver reso possibile tutto questo.<\/p>\n\n\n\n<p>\ud83d\ude4f Nel tentativo di costruire rapporti con la comunit\u00e0 locale, la nostra scuola ha stabilito una partnership con le scuole pubbliche locali di Silea, Roncade e Biancade. Il progetto, guidato dal professore Pitarresi, chiamato \"United through science\", permetter\u00e0 a gruppi di 20 studenti esterni di accedere ai nostri laboratori per lezioni pratiche di biologia e chimica alternate. 10 studenti DP 1 si sono offerti di insegnare agli studenti esterni, consentendo loro di acquisire nuove competenze. Questa esperienza vale per il loro programma CAS.&nbsp;<\/p>\n\n\n\n<p>\ud83c\udf97\ufe0fPer Service as Action vorremmo evidenziare la campagna di sensibilizzazione e raccolta fondi per il ripristino dei coralli condotta dalla nostra studentessa MYP 2 Olivia Stella. Il suo progetto prevede una conferenza personalizzata con il biologo marino e il coordinatore scientifico del progetto e una raccolta fondi per la <a href=\"https:\/\/www.coralrestorationferidhoomaldives.org\/\" target=\"_blank\" rel=\"noopener\">Coral Restoration Feridhoo Maldives<\/a>. Ulteriori dettagli nel poster <a href=\"https:\/\/drive.google.com\/file\/d\/1uuTwzm9t0wE8bYtAHvwZVnAl4Ws6xld-\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>\ud83d\ude4f In preparation of the Black History Awareness Month which is held in February, our students have worked on a CAS project showcasing posters of notable people and their achievements.. Initiative poster here and black personalities posters here. \ud83c\udf97\ufe0fCalling for performers for the upcoming H-Farm Talent Show: Shine like the stars &amp; use the fun [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17596,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,11,51,52,53,54,55,1],"tags":[271,241,252],"week":[364],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/11\/H-FARM_11-2-14.27.42.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18321"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=18321"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18321\/revisions"}],"predecessor-version":[{"id":18324,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18321\/revisions\/18324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/17596"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=18321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=18321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=18321"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=18321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}