{"id":18563,"date":"2023-03-09T14:42:00","date_gmt":"2023-03-09T14:42:00","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=18563"},"modified":"2023-03-09T14:42:01","modified_gmt":"2023-03-09T14:42:01","slug":"orientation-careers-guidance-10","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/orientation-careers-guidance-10\/","title":{"rendered":"Orientamento &amp; Careers Guidance"},"content":{"rendered":"<p>Care famiglie delle classi MYP e DP, il Dipartimento di Orientamento \u00e8 lieto di presentare questi eventi:<\/p>\n\n\n\n<p><strong>\ud83d\udccc<\/strong> <strong>UNIFROG Webinar: Esplora in corsi in materie di sostenibilit\u00e0<\/strong><\/p>\n\n\n\n<p>Lo sapevate che i lavori con un focus sulla sostenibilit\u00e0 sono in aumento? Unitevi agli esperi di Harper Adams, Huddersfield e della Royal Agricultural University <strong>mercoled\u00ec 15 marzo alle 18:00<\/strong> per esplorare una serie di corsi di laurea incentrati sulla lotta ai cambiamenti climatici e alle sfide ambientali, tra cui produzione alimentare e l'ingegneria. Accedere al proprio account UNIFROG per seguire alla presentazione.<\/p>\n\n\n\n<p><strong>\ud83d\udccc &nbsp;MYP5-DP 1: Presentation <\/strong><a href=\"https:\/\/international.ucam.edu\/\" target=\"_blank\" rel=\"noopener\"><strong>UCAM<\/strong><\/a><strong> <\/strong>&#8211; Thursday, 16th March 13:00-14:00, online&nbsp;<\/p>\n\n\n\n<p>Vi invitiamo alla presentazione di <a href=\"https:\/\/international.ucam.edu\/\">UCAM<\/a> per saperne di pi\u00f9 sull'offerta di 6 corsi di laurea in lingua inglese: <a href=\"https:\/\/international.ucam.edu\/studies\/bachelor-in-business-administration\" target=\"_blank\" rel=\"noopener\">Bachelor\u2019s Degree in Business Administration<\/a>, <a href=\"https:\/\/international.ucam.edu\/studies\/bachelor-in-dentistry-on-campus\" target=\"_blank\" rel=\"noopener\">Bachelor\u2019s Degree in Odontoiatria \u2013 (Murcia Campus)<\/a>, <a href=\"https:\/\/international.ucam.edu\/studies\/bachelor-in-modern-language\" target=\"_blank\" rel=\"noopener\">Bachelor\u2019s Degree in Lingue Moderne<\/a>, <a href=\"https:\/\/international.ucam.edu\/studies\/bachelor-in-psychology-on-campus\" target=\"_blank\" rel=\"noopener\">Bachelor\u2019s Degree in Psicologia<\/a>, <a href=\"https:\/\/international.ucam.edu\/studies\/bachelor-in-physical-activity-and-sport-sciences\" target=\"_blank\" rel=\"noopener\">Bachelor\u2019s Degree in Attivit\u00e0 Fisica e Scienze dello Sport<\/a>. Scoprite di pi\u00f9 sulle sedi dei campus, sui requisiti di ammissione, sulle opportunit\u00e0 di studio all'estero, sulla vita del campus e altro ancora. Gli studenti e le famiglie sono incoraggiati a partecipare.<\/p>\n\n\n\n<p><strong>Presentation Slides: DP 1 Kick Off Evening del 16 febbraio<\/strong>:<\/p>\n\n\n\n<p>Care famiglie delle classi DP 1, grazie per aver partecipato alla serata di Kick Off DP 1 del 16 febbrario! \u00c8 stato un piacere incontrare i genitori in Campus e connettersi con altri online. Potete vedere le slide della presentazione <a href=\"https:\/\/drive.google.com\/file\/d\/1dO26A3ogfKTyaSWGUfLKYrV1ytN9jMYa\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui<\/a>. Vi chiediamo di continuare ad incoraggiare i vostri ragazzi ad esplorare le molte risorse disponili in UNIFROG per la ricerca della propria carriera e di controllare la vostra casella di posta per non perdere i promemoria riguardo gli incontri individuali con le famiglie con la career counselor, Ms Ayana Fabris.&nbsp;<\/p>\n\n\n\n<p><strong>Informazioni sui Test Standardizzati<\/strong>:<\/p>\n\n\n\n<p>Molte universit\u00e0 americane considerano facoltativi i test per la classe 2024, ma non tutte. <a href=\"https:\/\/www.fairtest.org\/university\/optional\" target=\"_blank\" rel=\"noopener\">Controllate la lista qui<\/a>. Raccomandiamo a tutti gli studenti delle classi DP 1 di sostenere un test SAT prima della fine dell'anno scolastico se stanno pensando di fare domanda per gli Stati Uniti. Si prega di accedere a questo <a href=\"https:\/\/satsuite.collegeboard.org\/digital\/international-testing\/dates-deadlines\" target=\"_blank\" rel=\"noopener\">sito web<\/a> per controllare le date dei test internazionali e trovare un esempio di <a href=\"https:\/\/satsuite.collegeboard.org\/sat\/practice-preparation\/practice-tests\" target=\"_blank\" rel=\"noopener\">esami SAT<\/a>.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.valdoacademics.it\" target=\"_blank\" rel=\"noopener\">Valdo Academics<\/a> offre corsi di preparazione agli esami SAT; sono inclusi un corso estivo con inizio il 1 luglio (60 ore, inizio il 1 luglio, ogni mattina dal luned\u00ec al venerd\u00ec) e tutoraggio 1:1.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Presentazioni e registrazioni degli ultimi incontri con le universit\u00e0:<\/strong><\/p>\n\n\n\n<ul><li><a href=\"https:\/\/fsv.cuni.cz\/en\" target=\"_blank\" rel=\"noopener\">Facolt\u00e0 di Scienze Sociali, Charles University Prague<\/a>, <a href=\"https:\/\/drive.google.com\/file\/d\/17v3_qozxE9SnA-buxSbORNUY4WRxsqYc\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">presentazione qui<\/a>&nbsp;<\/li><li><a href=\"https:\/\/www.stmarys.ac.uk\/international\/home.aspx\" target=\"_blank\" rel=\"noopener\">St Mary University London<\/a>, webinar<a href=\"https:\/\/drive.google.com\/file\/d\/1-MI5x8OmBZ7jTtkSnvWKnSuulf0ZfjCV\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\"> qui<\/a> e presentazione <a href=\"https:\/\/drive.google.com\/file\/d\/1lu42U737Pwy391sEHWZpwmP6UJpuMmla\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui<\/a><\/li><li><a href=\"https:\/\/www.newschool.edu\/about\/\" target=\"_blank\" rel=\"noopener\">The New School Parsons<\/a>, presentazione <a href=\"https:\/\/docs.google.com\/presentation\/d\/1oulqJihzmwD4JbqtRGr2r-zSCk_gmJGU\/edit?usp=share_link&amp;ouid=110430725177235197493&amp;rtpof=true&amp;sd=true\" target=\"_blank\" rel=\"noopener\">qui<\/a>&nbsp;<\/li><li>European School of Economics \u2013 presentazione qui <a href=\"https:\/\/drive.google.com\/open?id=1Yn2yEw3DWeAOJS81W68_Ynwud2leWmUK&amp;authuser=enrollment@uniese.it&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">ESE Overview<\/a> e <a href=\"https:\/\/drive.google.com\/open?id=1Z7WavjRk345SgqN5DSyiLTTiMnmwAwnc&amp;authuser=enrollment@uniese.it&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">ESE Bsc Booklet<\/a><\/li><li>Glion Les Roches &#8211; <a href=\"https:\/\/drive.google.com\/open?id=17VYPoDCckQ6t4si2hwO61lJ7VPTJxk2W&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Brochure BBA Glion<\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1aAV0SX7iSOGWd4VfNgvjziEpgDtj_MdB&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Brochure BBA Les Roches <\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1kItWxdDGtufRBOu_3VlKckwuNkvq6atT&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Summer Programs<\/a><a href=\"https:\/\/drive.google.com\/open?id=1fOg3KMReo1trJfqgxWomXNXWe1z-ya4e&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\"> Glion<\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1ju2GzB5rkbHn1YiOZE4YHhJAqu3mA7HI&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Summer programs<\/a><a href=\"https:\/\/drive.google.com\/open?id=1j2jl3WbrzYBmiuDDhU6Nch_p0LJgNN7y&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\"> Les Roches<\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1liEQ75gL2oqQ8rpBCsbcA9zkuqCjWGHX&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">open day Glion<\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1q5vReLqLSef6d6FtaBxP_3ZidKD0zvxH&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">open day Les Roches<\/a><\/li><li>Donne nelle discipline STEM -<a href=\"https:\/\/www.fondazionebellisario.org\/progetto-stem\/\" target=\"_blank\" rel=\"noopener\"> progetto STEM<\/a> programma sperimentale da marzo a giugno 2023 per 20 studentesse delle classi MYP 5 e DP 1. Trovate <a href=\"https:\/\/drive.google.com\/file\/d\/1BCACC3cnJ3gKZvsExTz2tBbN0OPowBGQ\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui<\/a> il poster del workshop e <a href=\"https:\/\/drive.google.com\/file\/d\/1aBEtkHFSThbjlzvB2zHrch_fvb4rEGOn\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui<\/a> la presentazione della sessione di lancio.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Dear MYP and DP families, the Careers Guidance Department is pleased to feature the following events: \ud83d\udccc UNIFROG Webinar : Explore degrees in sustainability Did you know that jobs with a sustainability focus are on the rise? Join experts from Harper Adams, Huddersfield, and Royal Agricultural University on Wednesday 15th March at 18:00 to explore [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":16970,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,54,55],"tags":[400,237,151,209,310],"week":[412],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/09\/HIS_2022_08_29_Conan_Bighall_150_social.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18563"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=18563"}],"version-history":[{"count":4,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18563\/revisions"}],"predecessor-version":[{"id":18580,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/18563\/revisions\/18580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/16970"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=18563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=18563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=18563"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=18563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}