{"id":19137,"date":"2023-06-01T14:42:48","date_gmt":"2023-06-01T14:42:48","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=19137"},"modified":"2023-06-01T14:42:49","modified_gmt":"2023-06-01T14:42:49","slug":"orientation-careers-guidance-20","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/orientation-careers-guidance-20\/","title":{"rendered":"Orientamento &amp; Careers Guidance"},"content":{"rendered":"<p><strong>MYP 3 &#8211; DP 1: <\/strong><strong>Guida all'ammissione al college per studenti atleti - luned\u00ec 5 giugno, 17:30 - 18:30, online<\/strong><\/p>\n\n\n\n<p>Webinar offerto da <a href=\"https:\/\/www.air-recruiting.com\/\" target=\"_blank\" rel=\"noopener\">Air-Recruiting<\/a>.<\/p>\n\n\n\n<p>Il sogno di ogni studente-atleta \u00e8 quello di andare al college e praticare il proprio sport, ma il processo di ammissione al college pu\u00f2 sembrare scoraggiante. Con cos\u00ec tante cose a cui pensare e da realizzare - dalla stesura del profilo atletico alla partecipazione a eventi e all'assicurarsi che gli allenatori giusti vi vedano giocare - \u00e8 facile dimenticare il fatto che dovete effettivamente fare domanda di ammissione all'universit\u00e0. Partecipate a questo webinar di <a href=\"https:\/\/www.air-recruiting.com\/\" target=\"_blank\" rel=\"noopener\">Air-Recruiting <\/a>&nbsp;per ricevere importanti consigli su come affrontare il processo di ammissione al college come studenti-atleti. <\/p>\n\n\n\n<p>Vi preghiamo di utilizzare <a href=\"https:\/\/h-farm.webex.com\/h-farm\/j.php?MTID=m33fde259d017599e78ac4321a027bfef\" target=\"_blank\" rel=\"noopener\">questo link<\/a> per accedere al webinar <\/p>\n\n\n\n<p>Webinar password: HFarmSchool<\/p>\n\n\n\n<p>Panelist password: HFarmIntl23<\/p>\n\n\n\n<p><strong>MYP 5 \u2013 DP 1: <\/strong><a href=\"https:\/\/www.eventbrite.it\/e\/biglietti-4-segreti-1-per-scegliere-un-corso-universitario-627038909257\" target=\"_blank\" rel=\"noopener\"><strong>4 (+1) dritte su come scegliere la laurea triennale pi\u00f9 adatta a voi<\/strong><\/a><strong> - registrazione dell'incontro<\/strong><\/p>\n\n\n\n<p>Condividiamo <a href=\"https:\/\/h-farm.webex.com\/recordingservice\/sites\/h-farm\/recording\/playback\/9a11ebe2d559103baf6c16f48fd615a0\" target=\"_blank\" rel=\"noopener\">a questo link<\/a> la registrazione del meeting sulla scelta universitaria.<\/p>\n\n\n\n<p>Password di accesso: BzbVWKK2<\/p>\n\n\n\n<p><strong>H-Farm Summer School&nbsp;<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/courses.h-farm.com\/summer-school-2023\/\" target=\"_blank\" rel=\"noopener\">H-Farm Summer School<\/a> L'offerta 2023 \u00e8 pronta e quest'estate potrete scegliere tra un'ampia variet\u00e0 di argomenti che vanno dai corsi di consulenza universitaria, all'AI e allo sport. Assicuratevi di dare un'occhiata ai corsi esclusivi di quest'anno: <a href=\"https:\/\/courses.h-farm.com\/shop\/orientamento-universitario\/\" target=\"_blank\" rel=\"noopener\">College Counseling\/Orientamento Universitario<\/a> offre un'introduzione all'economia e alle scienze sociali tenuta da docenti di diverse prestigiose universit\u00e0 italiane; <a href=\"https:\/\/courses.h-farm.com\/shop\/master-week-in-gpt-app-development-eng\/\" target=\"_blank\" rel=\"noopener\">Master Week in GPT App Development<\/a> che copre i fondamenti della costruzione di applicazioni guidate dall'intelligenza artificiale, concentrandosi sulla progettazione incentrata sull'utente, sulla ricerca dei bisogni del prodotto e sulle tecniche di prototipazione, con l'insegnamento di Julia Markel, dottoranda a Stanford; oppure <a href=\"https:\/\/courses.h-farm.com\/shop\/golf-eng\/\" target=\"_blank\" rel=\"noopener\">Golf in English <\/a>un'esperienza di golf intensiva in collaborazione con il Golf Club Jesolo &amp; Venezia.&nbsp;<\/p>\n\n\n\n<p><strong>Summer Schools in Europa<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.summerschoolsineurope.eu\/\" target=\"_blank\" rel=\"noopener\">Summer Schools in Europe.eu<\/a> \u00e8 il catalogo pi\u00f9 completo di corsi estivi e invernali in Europa, suddivisi in 34 discipline accademiche e numerose localit\u00e0. Se non siete sicuri della disciplina che vorreste esplorare, potreste anche dare un'occhiata al sito <a href=\"https:\/\/www.summerschoolsineurope.eu\/topdestinations\" target=\"_blank\" rel=\"noopener\">Top Destinations<\/a> pagina in cui \u00e8 presente anche l'Italia con 3 inserzioni: <a href=\"https:\/\/www.summerschoolsineurope.eu\/school\/1703\/university-of-pisa-summer-school\" target=\"_blank\" rel=\"noopener\">University of Pisa Summer School<\/a>, <a href=\"https:\/\/www.unibocconi.eu\/wps\/wcm\/connect\/bocconi\/sitopubblico_en\/navigation+tree\/home\/programs\/summer+school\" target=\"_blank\" rel=\"noopener\">Bocconi Summer School<\/a> e <a href=\"https:\/\/www.summerschoolsineurope.eu\/school\/66\/ied-summer-courses\" target=\"_blank\" rel=\"noopener\">IED Summer Courses<\/a>. Non perdete questa occasione e iniziate a pianificare la vostra estate: un corso estivo incide sia sul vostro CV per le domande di ammissione all'universit\u00e0 sia sul vostro portfolio CAS!<\/p>\n\n\n\n<p><strong>Informazioni sui Test Standardizzati&nbsp;<\/strong><\/p>\n\n\n\n<p>Molte universit\u00e0 americane considerano facoltativi i test per la classe 2024, ma non tutte. <a href=\"https:\/\/www.fairtest.org\/university\/optional\" target=\"_blank\" rel=\"noopener\">Controllate la lista qui<\/a>. Raccomandiamo a tutti gli studenti delle classi DP 1 di sostenere un test SAT prima della fine dell'anno scolastico se stanno pensando di fare domanda per gli Stati Uniti. Si prega di accedere a questo <a href=\"https:\/\/satsuite.collegeboard.org\/digital\/international-testing\/dates-deadlines\" target=\"_blank\" rel=\"noopener\">sito web<\/a> per controllare le date dei test internazionali e trovare un esempio di <a href=\"https:\/\/satsuite.collegeboard.org\/sat\/practice-preparation\/practice-tests\" target=\"_blank\" rel=\"noopener\">esami SAT<\/a>.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.valdoacademics.it\" target=\"_blank\" rel=\"noopener\">Valdo Academics<\/a> offre corsi di preparazione agli esami SAT; sono inclusi un corso estivo con inizio il 1 luglio (60 ore, inizio il 1 luglio, ogni mattina dal luned\u00ec al venerd\u00ec) e tutoraggio 1:1.&nbsp;<\/p>\n\n\n\n<p><strong>Presentazioni e registrazioni degli ultimi incontri con le universit\u00e0:<\/strong><\/p>\n\n\n\n<ul><li><a href=\"https:\/\/fsv.cuni.cz\/en\" target=\"_blank\" rel=\"noopener\">Facolt\u00e0 di Scienze Sociali, Charles University Prague<\/a>, <a href=\"https:\/\/drive.google.com\/file\/d\/17v3_qozxE9SnA-buxSbORNUY4WRxsqYc\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">presentazione qui<\/a>&nbsp;<\/li><li><a href=\"https:\/\/www.stmarys.ac.uk\/international\/home.aspx\" target=\"_blank\" rel=\"noopener\">St Mary University London<\/a>, webinar<a href=\"https:\/\/drive.google.com\/file\/d\/1-MI5x8OmBZ7jTtkSnvWKnSuulf0ZfjCV\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\"> qui<\/a> e presentazione <a href=\"https:\/\/drive.google.com\/file\/d\/1lu42U737Pwy391sEHWZpwmP6UJpuMmla\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui<\/a><\/li><li><a href=\"https:\/\/www.newschool.edu\/about\/\" target=\"_blank\" rel=\"noopener\">The New School Parsons<\/a>, presentazione <a href=\"https:\/\/docs.google.com\/presentation\/d\/1oulqJihzmwD4JbqtRGr2r-zSCk_gmJGU\/edit?usp=share_link&amp;ouid=110430725177235197493&amp;rtpof=true&amp;sd=true\" target=\"_blank\" rel=\"noopener\">qui<\/a>&nbsp;<\/li><li>European School of Economics \u2013 presentazione qui <a href=\"https:\/\/drive.google.com\/open?id=1Yn2yEw3DWeAOJS81W68_Ynwud2leWmUK&amp;authuser=enrollment@uniese.it&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">ESE Overview<\/a> e <a href=\"https:\/\/drive.google.com\/open?id=1Z7WavjRk345SgqN5DSyiLTTiMnmwAwnc&amp;authuser=enrollment@uniese.it&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">ESE Bsc Booklet<\/a><\/li><li>Glion Les Roches &#8211; <a href=\"https:\/\/drive.google.com\/open?id=17VYPoDCckQ6t4si2hwO61lJ7VPTJxk2W&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Brochure BBA Glion<\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1aAV0SX7iSOGWd4VfNgvjziEpgDtj_MdB&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Brochure BBA Les Roches <\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1kItWxdDGtufRBOu_3VlKckwuNkvq6atT&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Summer Programs<\/a><a href=\"https:\/\/drive.google.com\/open?id=1fOg3KMReo1trJfqgxWomXNXWe1z-ya4e&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\"> Glion<\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1ju2GzB5rkbHn1YiOZE4YHhJAqu3mA7HI&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Summer programs<\/a><a href=\"https:\/\/drive.google.com\/open?id=1j2jl3WbrzYBmiuDDhU6Nch_p0LJgNN7y&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\"> Les Roches<\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1liEQ75gL2oqQ8rpBCsbcA9zkuqCjWGHX&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">open day Glion<\/a>; <a href=\"https:\/\/drive.google.com\/open?id=1q5vReLqLSef6d6FtaBxP_3ZidKD0zvxH&amp;authuser=marta.toncelli@ec.sommet-education.com&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">open day Les Roches<\/a><\/li><li>Donne nelle discipline STEM -<a href=\"https:\/\/www.fondazionebellisario.org\/progetto-stem\/\" target=\"_blank\" rel=\"noopener\"> progetto STEM<\/a> programma sperimentale da marzo a giugno 2023 per 20 studentesse delle classi MYP 5 e DP 1. Trovate <a href=\"https:\/\/drive.google.com\/file\/d\/1BCACC3cnJ3gKZvsExTz2tBbN0OPowBGQ\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui<\/a> il poster del workshop e <a href=\"https:\/\/drive.google.com\/file\/d\/1aBEtkHFSThbjlzvB2zHrch_fvb4rEGOn\/view?usp=share_link\" target=\"_blank\" rel=\"noopener\">qui<\/a> la presentazione del progetto. Le presentazioni tenute finora sono <a href=\"https:\/\/docs.google.com\/presentation\/d\/19d1w4iEhyDJvBVY1rR3esHsI11QZuDBMOuenSi6d51U\/edit?usp=share_link\" target=\"_blank\" rel=\"noopener\">Valorizzare il proprio talento<\/a>, <a href=\"https:\/\/docs.google.com\/presentation\/d\/1JXy5ESwAFSoTerjB3gChxCsZLIahsAVw2biP4rTC5w4\/edit?usp=share_link\" target=\"_blank\" rel=\"noopener\">Fare della propria carriera un capolavoro<\/a>.&nbsp;<\/li><li><a href=\"https:\/\/www.ucam.edu\/\" target=\"_blank\" rel=\"noopener\">UCAM<\/a>, presentazione <a href=\"https:\/\/docs.google.com\/presentation\/d\/11JXFJJFhwBNxHgVplKqM-Jnlt3EaUxAn\/edit?usp=share_link&amp;ouid=110430725177235197493&amp;rtpof=true&amp;sd=true\" target=\"_blank\" rel=\"noopener\">qui<\/a>. <a href=\"https:\/\/www.ucam.edu\/sites\/default\/files\/documentos\/folletos-estudios\/italian_ucam-programs-brochur.pdf\" target=\"_blank\" rel=\"noopener\">Brochure con offerta formativa<\/a> in italiano, <a href=\"https:\/\/docs.google.com\/presentation\/d\/e\/2PACX-1vSpt3CiazjlVk3rbyPSDlKdyjenib6NLYjfq477NDRr3huH4PRwxrslNgQR18uFEYthCyY1ECZf7Fq9\/pub?start=true&amp;loop=true&amp;delayms=3000&amp;slide=id.g1d7399e324b_0_64\" target=\"_blank\" rel=\"noopener\">Presentazione con breve descrizione sul processo di ammissione UCAM per gli studenti provenienti dall&#8217;Italia<\/a>.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>MYP 3 &#8211; DP 1: College Admission Guide for Student Athletes &#8211; Monday, 5th June, 17:30 &#8211; 18:30, online Webinar offered by Air-Recruiting. Every student-athlete\u2019s dream is to go on to college and play their sport, but the college admissions process can seem daunting. With so much to think about and accomplish &#8211; from putting [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":16970,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,54,55],"tags":[400,237,151,209,310],"week":[521],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/09\/HIS_2022_08_29_Conan_Bighall_150_social.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/19137"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=19137"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/19137\/revisions"}],"predecessor-version":[{"id":19139,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/19137\/revisions\/19139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/16970"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=19137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=19137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=19137"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=19137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}