{"id":19531,"date":"2023-09-21T15:33:07","date_gmt":"2023-09-21T15:33:07","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=19531"},"modified":"2023-09-21T15:33:08","modified_gmt":"2023-09-21T15:33:08","slug":"orientamento-e-consulenza-professionale-3","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/orientation-and-careers-guidance-3\/","title":{"rendered":"Orientamento e Careers Guidance"},"content":{"rendered":"<p class=\"has-text-align-center\"><strong>MYP5-DP1-DP2: Processo di candidatura per i Paesi Bassi - Marted\u00ec 26 settembre, <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">NUOVO ORARIO 17:45<\/mark><\/strong><\/p>\n\n\n\n<p>Valdo Academics e H Guidance Counselors condivideranno informazioni su come fare domanda alle universit\u00e0 olandesi. Il workshop sar\u00e0 condotto da Lonnie Holders, esperto olandese di applicazioni, del team di Valdo Academics, che fornir\u00e0 una panoramica del sistema olandese, i requisiti di ingresso per i programmi numerus fixus (come psicologia) e le linee guida su come scrivere lettere di motivazione quando richiesto.<\/p>\n\n\n\n<p>Le famiglie che parteciperanno all'evento \"Back to School Night\" potranno seguire l'incontro direttamente in Campus<\/p>\n\n\n\n<p>Gli altri potranno unirsi online <a href=\"https:\/\/h-farm.webex.com\/h-farm\/j.php?MTID=mcaa8b9f9cd09fed6a6453e89eca5f874\" target=\"_blank\" rel=\"noopener\">a questo link<\/a>.<\/p>\n\n\n\n<p>Password del webinar: Olanda23&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>MYP5 - DP2: Open House dell'Universit\u00e0 Americana di Roma <strong>28<\/strong><\/strong> <strong>settembre alle 19:00, online<\/strong><\/p>\n\n\n\n<p>Appello a tutti gli studenti con una mentalit\u00e0 internazionale!<strong> <\/strong><a href=\"https:\/\/admissions.aur.edu\/e\/271252\/2023-08-30\/3l23p5\/728592271?h=sycfJWOwHYHNFoCHjzGyrnpnuTpHHm3osVfDpMGoRMs\" target=\"_blank\" rel=\"noopener\"><strong>L'Universit\u00e0 Americana di Roma<\/strong><\/a><strong> <\/strong>ospita un'Open House virtuale. Si tratta di un'opportunit\u00e0 interessante per tutti i vostri studenti internazionali alla ricerca di un corso di laurea accreditato negli Stati Uniti in Europa. In questa sessione, voi e tutti gli studenti interessati potrete esplorare<strong> <\/strong>L'offerta accademica dell'AUR e le opportunit\u00e0 di vita degli studenti; scoprire<strong> <\/strong>i vantaggi dell'apprendimento esperienziale a Roma, in Italia, e oltre; e lasciatevi ispirare dalla variegata e dinamica comunit\u00e0 di esploratori globali dell'AUR. Per l'evento \u00e8 necessaria la registrazione. <a href=\"https:\/\/aur.edu\/news\/openhouse-september23\" target=\"_blank\" rel=\"noopener\">registrarvi qui<\/a>.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>MYP5 \u2013 DP2 <\/strong><a href=\"https:\/\/www.careerdays.co.uk\/apply-now\/performing-arts-work-experience-and-careers-day\" target=\"_blank\" rel=\"noopener\"><strong>Performing Arts Work Experience e Careers Day<\/strong><\/a><strong> - sabato, <strong>30<\/strong><\/strong> <strong>settembre dalle 11:00 alle 16:00, ONLINE<\/strong><\/p>\n\n\n\n<p>Per tutti gli studenti che sognano una carriera nelle arti dello spettacolo, la nostra giornata dedicata alle carriere e all'esperienza lavorativa nelle arti dello spettacolo vi aiuter\u00e0 a decidere se \u00e8 la carriera che fa per voi, vi far\u00e0 fare un'esperienza di lavoro e vi aiuter\u00e0 con le vostre candidature. Discuteremo di tutte le opzioni a tua disposizione e di cosa devi fare esattamente per ottenere l'inafferrabile posto di formazione. Nel pomeriggio, il nostro team divider\u00e0 tutti in gruppi e lavoreremo insieme a un esercizio che vi metter\u00e0 al centro dell'industria, consentendovi di vedere una produzione da tutte le angolazioni. Al momento di presentare la domanda di ammissione, dovrete conoscere il percorso esatto da seguire per avere successo in una carriera nelle arti dello spettacolo e dimostrare di aver fatto ricerche approfondite su questa carriera. La registrazione \u00e8 obbligatoria, <a href=\"https:\/\/www.careerdays.co.uk\/apply-now\/performing-arts-work-experience-and-careers-day\" target=\"_blank\" rel=\"noopener\">registrarvi qui<\/a>.<\/p>\n\n\n\n<p>Questo corso \u00e8 offerto da <a href=\"https:\/\/www.careerdays.co.uk\/\">CareerDays.it<\/a>. <a href=\"https:\/\/www.careerdays.co.uk\/about-us\">A questo link<\/a> potete trovare pi\u00f9 informazioni riguardo l'organizzazione e come opera.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Presentazioni e registrazioni passate di questo semestre<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/1sxdhRsFS02LY_5JxcOxZP7j3lwEdztt7\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\">Workshop per candidati ad universit\u00e0 USA sulla scrittura di un saggio universitario<\/a> Registrazione, per gentile concessione di <a href=\"\/it\/www.valdoacademics.com\/\" target=\"_blank\" rel=\"noopener\">Valdo Academics&nbsp;<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/docs.google.com\/presentation\/d\/1zK98vbmVtGh9id2DO7dfMelEFaD4EO3-6i6vH7_YEZI\/edit?usp=sharing\" target=\"_blank\" rel=\"noopener\">DP2 Presentazione della domanda di ammissione all'universit\u00e0<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/drive.google.com\/drive\/u\/0\/folders\/1SaVO-4VT9GBUAqMpQuzI-vpyCUu8q-r2\" target=\"_blank\" rel=\"noopener\">MYP5-DP2:Workshop sulla dichiarazione personale<\/a> della Warwick University<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>","protected":false},"excerpt":{"rendered":"<p>MYP5-DP1-DP2: Application process for the Netherlands &#8211; Tuesday, 26th September, NEW TIME Schedule 5:45 Valdo Academics and H Guidance Counselors will share information on how to apply to Dutch Universities. The workshop will be led by Dutch applications expert Lonnie Holders from the Valdo Academics team, who will provide an overview of the Dutch system, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":19422,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,55],"tags":[586,152,584,503,585,151,156,310],"week":[606],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2023\/09\/HIS_First_Day_School_2023_09_05_67-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/19531"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=19531"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/19531\/revisions"}],"predecessor-version":[{"id":19535,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/19531\/revisions\/19535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/19422"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=19531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=19531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=19531"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=19531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}