{"id":20566,"date":"2024-03-07T14:20:18","date_gmt":"2024-03-07T14:20:18","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=20566"},"modified":"2024-03-07T14:31:21","modified_gmt":"2024-03-07T14:31:21","slug":"boarding-experience-boot-camp","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/boarding-experience-boot-camp\/","title":{"rendered":"Boot Camp: Vivi un'esperienza in Boarding"},"content":{"rendered":"<p><em>Sentirsi a casa lontano da casa<\/em><\/p>\n\n\n\n<p>Partecipazione alle iniziative di H-FARM (storming pizza, conferenze); sviluppo di relazioni entusiasmanti con coetanei e adulti significativi che permettano di sviluppare le loro capacit\u00e0 relazionali; partecipazione a esperienze extrascolastiche arricchenti avendo a disposizione tempi precisi e un supporto qualificato per prepararsi a livello accademico: tutto questo \u00e8 l'esperienza in cui i vostri figli potranno immergersi in questa settimana in Boarding.<\/p>\n\n\n\n<p>Cosa: Boot Camp Vivi un'esperienza in Boarding&nbsp;<\/p>\n\n\n\n<p>Quando: 12-19 aprile, 2024<\/p>\n\n\n\n<p>Chi: studenti diurni della scuola secondaria (MYP3-DP1) - Numero di posti limitato per 10-20 studenti<\/p>\n\n\n\n<p>Costo: 500\u20ac<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Programma proposto:<\/strong><\/p>\n\n\n\n<p><strong>Venerd\u00ec sera<\/strong><\/p>\n\n\n\n<p>16:30 - Benvenuto al Bootcamp e introduzione al programma<br>18:00 - Club di cucina<\/p>\n\n\n\n<p><strong>Sabato:<\/strong>Sport: Rafting in Valsugana (o HyperSpace in caso di pioggia)<\/p>\n\n\n\n<p>07:00 - 09:00 - Colazione<\/p>\n\n\n\n<p>09:30 - 18:00 - Gita presso HyperSpace<\/p>\n\n\n\n<p>18:00 - 19:30 - Riposo e relax<\/p>\n\n\n\n<p>19:30 - 20:30 - Cena<\/p>\n\n\n\n<p>20:30 - 23:00 - Attivit\u00e0 sportive nella Cisco Arena e giochi nella sala comune<\/p>\n\n\n\n<p>23:00 - Coprifuoco (gli studenti dovranno essere nelle loro stanze)<\/p>\n\n\n\n<p><strong>Domenica:<\/strong>&nbsp;&nbsp;<\/p>\n\n\n\n<p>07:00 - 09:00 - Colazione self-service<\/p>\n\n\n\n<p>9:00 &#8211; 11:00 am&nbsp; &#8211; Chill &amp; Relax<\/p>\n\n\n\n<p>11:00 - 14:00 - Brunch<\/p>\n\n\n\n<p>14:30 - 17:30 - Visita al centro commerciale Valecenter&nbsp;<\/p>\n\n\n\n<p>17:30 - 19:30 - Tempo per lo studio - Tempo libero per lo sport - Benvenuto agli studenti 5\/7<\/p>\n\n\n\n<p>19:30 - 20:30 - Cena<\/p>\n\n\n\n<p>20.30 - 22:00 - Giochi nella sala comune, relax e conversazione<\/p>\n\n\n\n<p>22:00 - Coprifuoco (gli studenti dovranno essere nelle loro stanze)<\/p>\n\n\n\n<p><strong>Luned\u00ec - Gioved\u00ec:&nbsp;<\/strong><\/p>\n\n\n\n<p>16:30 - Attivit\u00e0 doposcuola o sportive o relax<\/p>\n\n\n\n<p>18:00 - 19:30 - Studio assistito con insegnanti<\/p>\n\n\n\n<p>7:30 &#8211; 8:30 pm &#8211;&nbsp; Dinner<\/p>\n\n\n\n<p>20:30 - 22:00 - Tempo libero (sport, attivit\u00e0, studio, club, ecc)<\/p>\n\n\n\n<p>22:00 - Coprifuoco (gli studenti dovranno essere nelle loro stanze)<\/p>\n\n\n\n<p><strong>Proposta di club settimanali:<\/strong><\/p>\n\n\n\n<p>Luned\u00ec: Club giochi da tavolo o Club di nail design<\/p>\n\n\n\n<p>Marted\u00ec: Club di badminton<\/p>\n\n\n\n<p>Mercoled\u00ec: Basket, Pallavolo o Arte<\/p>\n\n\n\n<p>Gioved\u00ec: Club di musica o allenamento di basket<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Dettagli per l'iscrizione:<\/strong><\/p>\n\n\n\n<p>Scadenza: Accedete alla <a href=\"https:\/\/www.h-is.com\/application\/product-list\/trips\" target=\"_blank\" rel=\"noopener\">piattaforma H-FARM<\/a>, selezionate \"Boarding Experience Bootcamp\" e confermate la partecipazione di vostro figlio entro il 5 aprile.<\/p>\n\n\n\n<p>Non perdetevi questa opportunit\u00e0 per provare il nostro boarding!<\/p>","protected":false},"excerpt":{"rendered":"<p>A home away from home Participate in H-FARM initiatives (storming pizzas, conferences); develop exciting relationships with peers and significant adults that allow them to develop their interpersonal skills; participate in enriching extracurricular experiences while having precise time and qualified support to prepare academically: all of this is the experience that your children can immerse themselves [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":20576,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[59,11,53,54,55],"tags":[766,832,385,241,68,897,209,156],"week":[886],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/03\/H-IS-Bootcamp_1920-x-1080-01.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/20566"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=20566"}],"version-history":[{"count":4,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/20566\/revisions"}],"predecessor-version":[{"id":20577,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/20566\/revisions\/20577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/20576"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=20566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=20566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=20566"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=20566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}