{"id":20971,"date":"2024-05-23T11:06:03","date_gmt":"2024-05-23T11:06:03","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=20971"},"modified":"2024-05-23T11:10:51","modified_gmt":"2024-05-23T11:10:51","slug":"summer-book-fair-sale-monday-june-3","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/summer-book-fair-sale-monday-june-3\/","title":{"rendered":"Fiera e vendita di libri PYP per l\u2019estate - luned\u00ec 3 giugno"},"content":{"rendered":"<p>Ecco una fantastica opportunit\u00e0 per acquistare libri per le letture estive!<\/p>\n\n\n\n<p>Tutti gli studenti PYP visiteranno la Book Sale durante la giornata di luned\u00ec 3 giugno. In media, i libri costano circa 8\/9 euro l'uno. Le MONETE sono ben accette. Assicuratevi che il denaro di vostro figlio sia in una busta sigillata, con il suo nome scritto sopra.<\/p>\n\n\n\n<p>Anche i genitori potranno visitare la Book Sale nell'aula di italiano dalle 15:00 alle 16:30. Sono accettate anche carte di credito.<\/p>","protected":false},"excerpt":{"rendered":"<p>This is a wonderful opportunity to purchase books for Summer Reading! All PYP students will visit the book sale during the day on Monday June 3rd. On average, books cost approximately 8\/9 euro each. COINS are very welcome. Please ensure your child\u2019s money is in a sealed envelope, labelled with their name. Parents can visit [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20972,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58],"tags":[248,471,249,250,404],"week":[998],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/05\/Book-Fair-June.png","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/20971"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=20971"}],"version-history":[{"count":3,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/20971\/revisions"}],"predecessor-version":[{"id":21004,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/20971\/revisions\/21004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/20972"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=20971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=20971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=20971"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=20971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}