{"id":21401,"date":"2024-08-29T16:11:02","date_gmt":"2024-08-29T16:11:02","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=21401"},"modified":"2024-08-29T16:11:02","modified_gmt":"2024-08-29T16:11:02","slug":"school-bus-service-2","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/school-bus-service-2\/","title":{"rendered":"Servizio bus scolastico"},"content":{"rendered":"<p>Gentili famiglie,<\/p>\n\n\n\n<p>Vi segnaliamo che sono rimasti solo pochi posti su alcune linee di scuolabus e che le iscrizioni saranno accettate fino a domani, 30 agosto alle 12:00.<\/p>\n\n\n\n<p>\u00c8 ancora possibile bloccare un posto a sedere per il proprio figlio sulle seguenti linee di autobus:<\/p>\n\n\n\n<ul><li><strong>Green Line Treviso<\/strong><\/li><li><strong>White Line Treviso <\/strong>(pochi posti disponibili)<\/li><li><strong>Red Line Venice<\/strong><\/li><li><strong>Orange Line Mestre <\/strong>(pochi posti disponibili)<\/li><li><strong>Blue Line Padova<\/strong><\/li><li><strong>Pink Line Marcon <\/strong>(1 posto disponibile)<\/li><\/ul>\n\n\n\n<p>Le seguenti linee sono al completo:<\/p>\n\n\n\n<ul><li>Gold Line Cavallino, Jesolo<\/li><li>Teal Line Oderzo, Fossalta<\/li><li>Purple Line Conegliano<\/li><\/ul>\n\n\n\n<p>Scriveteci a <a href=\"mailto:office.ve@h-is.com\" target=\"_blank\" rel=\"noopener\">office.ve@h-is.com<\/a> per iscrivere vostro figlio al servizio di scuolabus.<\/p>\n\n\n\n<p>Per coloro che hanno gi\u00e0 confermato il servizio, domani verranno forniti ulteriori dettagli. Si ricorda inoltre che il pagamento sar\u00e0 possibile a partire dal 15 settembre.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dear Families, Please note that there are only a few seats remaining on certain school bus lines, and we will be accepting registrations until tomorrow, August 30th, at 12:00 PM. You may still secure a seat for your child on the following bus routes: Green Line Treviso White Line Treviso (few seats available) Red Line [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":21244,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,11,51,52,53,54,55,8,62,63,64,49,50,56,57,58],"tags":[298,558,559],"week":[1066],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/07\/HIS_SchoolBus_2023_5_social.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21401"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=21401"}],"version-history":[{"count":1,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21401\/revisions"}],"predecessor-version":[{"id":21402,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21401\/revisions\/21402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/21244"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=21401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=21401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=21401"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=21401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}