{"id":21501,"date":"2024-09-19T13:45:17","date_gmt":"2024-09-19T13:45:17","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=21501"},"modified":"2024-09-19T13:45:18","modified_gmt":"2024-09-19T13:45:18","slug":"pta-event-aperitivo-friday-september-27th","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/pta-event-aperitivo-friday-september-27th\/","title":{"rendered":"Evento PTA: aperitivo - venerd\u00ec 27 settembre"},"content":{"rendered":"<p>Le famiglie di H-FARM sono invitate a unirsi a noi a The Hill (la grande biblioteca) in Campus per brindare a momenti di allegria e belle vibrazioni! Anche i vostri animali domestici sono i benvenuti!<\/p>\n\n\n\n<p>Quando? <strong>venerd\u00ec 27 settembre, dalle 16.30<\/strong><br>Dove? <strong>The Hill, Campus H-FARM<\/strong><\/p>\n\n\n\n<p>Festeggiamo l'inizio dell'anno scolastico 2024-25! Unitevi a noi a The Hill, presso il Campus H-FARM, per una deliziosa serata a base di bevande, spuntini e ottima compagnia. Il nostro evento \u00e8 l'occasione perfetta per rilassarsi dopo una lunga giornata, conoscere nuove persone e godersi la splendida cornice del campus. Non perdete l'occasione di socializzare e divertirvi in un ambiente rilassato.<\/p>\n\n\n\n<p>Registratevi utilizzando <a href=\"https:\/\/www.eventbrite.com\/e\/biglietti-aperitivo-1021520434117?aff=oddtdtcreator\" target=\"_blank\" rel=\"noopener\">questo link<\/a>.<\/p>\n\n\n\n<p>La quota di partecipazione \u00e8 di 22,50\u20ac per adulto (i bambini non pagano) e comprende aperitivo e snack.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster-724x1024.jpg\" alt=\"\" class=\"wp-image-21505\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster-724x1024.jpg 724w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster-212x300.jpg 212w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster-768x1086.jpg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster-1086x1536.jpg 1086w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster-1448x2048.jpg 1448w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster-8x12.jpg 8w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster-1357x1920.jpg 1357w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/PTA-poster.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>H-FARM families are invited to come to the Hill (the big library) by the H-FARM campus to toast to good times and vibes! Feel free to bring your pets! When? Friday September 27th, 4:30 PMWhere? The Hill, H-FARM Campus Let&#8217;s celebrate the beginning of the 2024-25 school year! Come join us at The Hill by [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21507,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[458,6,59,60,11,51,52,53,54,55,8,62,63,64,49,50,56,57,58],"tags":[1113,241,68,149,209],"week":[1110],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-18-at-14.40.56.png","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21501"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=21501"}],"version-history":[{"count":3,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21501\/revisions"}],"predecessor-version":[{"id":21519,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21501\/revisions\/21519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/21507"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=21501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=21501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=21501"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=21501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}