{"id":21581,"date":"2024-09-26T13:43:02","date_gmt":"2024-09-26T13:43:02","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=21581"},"modified":"2024-09-26T13:43:03","modified_gmt":"2024-09-26T13:43:03","slug":"a-message-from-anthony-2","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/a-message-from-anthony-2\/","title":{"rendered":"Un messaggio da Anthony"},"content":{"rendered":"<p>Il PYP sta entrando nel vivo con visite didattiche, workshop per genitori e mattinate a porte aperte per tutti gli year level. Chiediamo ai genitori di impegnarsi a provare a partecipare alle giornate aperte, alle celebrazioni dell'apprendimento e agli eventi che si svolgeranno durante l'anno, ma sappiamo che non \u00e8 sempre possibile. Fateci sapere quando <strong>non potete partecipare<\/strong> e cercheremo di organizzare un \u201csostituto genitore\u201d per l'evento, che pu\u00f2 essere un altro insegnante o uno studente pi\u00f9 grande che lo studente conosce.<br>Poich\u00e9 le nostre valutazioni preliminari stanno per terminare, gli insegnanti stanno utilizzando questi dati per informarvi dell'apprendimento che avviene in classe. Se avete bisogno di qualsiasi informazione accademica, contattate gli insegnanti di classe o gli insegnanti specialisti, siamo sempre felici di parlare dell'apprendimento di vostro figlio!<\/p>","protected":false},"excerpt":{"rendered":"<p>The PYP is starting to get into full swing, with field trips, parent workshops and open mornings happening across the year levels. We ask that parents try to commit to attending our open days \/ celebrations of learning \/ events that may arise across the year, but we know this is not always possible. Please [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21359,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58],"tags":[1095,1034,1072,236],"week":[1123],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/08\/H-IS_HAMBLIN_ANTHONY-JOSEPH_2024_7_social.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21581"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=21581"}],"version-history":[{"count":1,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21581\/revisions"}],"predecessor-version":[{"id":21583,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21581\/revisions\/21583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/21359"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=21581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=21581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=21581"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=21581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}