{"id":21633,"date":"2024-10-03T13:14:13","date_gmt":"2024-10-03T13:14:13","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=21633"},"modified":"2024-10-03T13:14:14","modified_gmt":"2024-10-03T13:14:14","slug":"managebac-how-to-check-your-childs-timetable-and-attendance","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/managebac-how-to-check-your-childs-timetable-and-attendance\/","title":{"rendered":"ManageBac: come controllare l'orario e il registro presenze di vostro figlio"},"content":{"rendered":"<p>Controllare regolarmente l'orario e le presenze di vostro figlio su ManageBac \u00e8 una parte essenziale per rimanere informati sul suo percorso scolastico. Poich\u00e9 ManageBac non invia automaticamente le notifiche relative alle presenze, \u00e8 fondamentale che i genitori prendano l'iniziativa di monitorare questi aspetti. In questo modo \u00e8 possibile risolvere tempestivamente eventuali problemi, come le lezioni perse o le modifiche all'orario.<\/p>\n\n\n\n<p>ManageBac offre ai genitori un modo semplice per rimanere aggiornati sugli orari e sulle presenze dei propri figli. Ecco una guida rapida su come accedere a queste informazioni:<\/p>\n\n\n\n<p><strong>1. Accedi a ManageBac<\/strong><\/p>\n\n\n\n<p><strong>2. Vai al profilo accademico di tuo figlio.<\/strong><\/p>\n\n\n\n<p><strong>3. Vai alla sezione Attendance &amp; Timetable.<\/strong><\/p>\n\n\n\n<p><strong>4. Consulta l'orario e i registri di presenza di tuo figlio per avere una visione dettagliata.<\/strong><\/p>\n\n\n\n<p>In ManageBac, le presenze sono codificate per colore:&nbsp;<\/p>\n\n\n\n<ul><li><mark style=\"background-color:#6ECA09\" class=\"has-inline-color\">Verde<\/mark>: Presente<\/li><li><mark style=\"background-color:#15c7ff\" class=\"has-inline-color\">Blu<\/mark>: Assente giustificato<\/li><li><mark style=\"background-color:#FAB901\" class=\"has-inline-color has-black-color\">Giallo<\/mark>: In ritardo<\/li><li><mark style=\"background-color:#D0021B\" class=\"has-inline-color has-black-color\">Rosso<\/mark>: Assente non giustificato<\/li><li><mark style=\"background-color:#e2e2e2\" class=\"has-inline-color\">Grigio<\/mark>: Presenze non ancora registrate<\/li><\/ul>\n\n\n\n<p>Controllando i colori nella sezione presenze del profilo accademico di vostro figlio su ManageBac, potrete facilmente monitorare il suo stato di presenza giornaliera e intervenire quando necessario.<\/p>\n\n\n\n<p>Ulteriori informazioni su come utilizzare ManageBac come genitore sono disponibili <a href=\"https:\/\/help.managebac.com\/hc\/en-us\/sections\/360008401972#parent-journey\" target=\"_blank\" rel=\"noopener\">qui<\/a>.<\/p>\n\n\n\n<div class=\"wp-container-2 wp-block-group\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-container-1 is-vertical wp-block-group\">\n<p>Vi ricordiamo che <strong>tutte le assenze devono essere giustificate entro le 08:30,<\/strong> e che c'\u00e8 un limite massimo di assenze consentite durante l'anno accademico:<\/p>\n\n\n\n<p>20% per MYP<\/p>\n\n\n\n<p>15% per DP<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p>I permessi personali per motivi non urgenti, come le vacanze in famiglia, sono sconsigliati e vanno contro la politica scolastica. Se i genitori scelgono di ritirare il proprio figlio per una vacanza in famiglia, lo fanno con la consapevolezza che i voti del figlio potrebbero essere influenzati negativamente e che non ci sar\u00e0 alcuna indennit\u00e0 per le ore o le valutazioni perse.<\/p>","protected":false},"excerpt":{"rendered":"<p>Regularly checking your child&#8217;s timetable and attendance on ManageBac is an essential part of staying informed about their academic journey. Since ManageBac does not automatically send notifications about attendance records, it&#8217;s crucial for parents to take the initiative in monitoring these aspects. This ensures you can address any issues, such as missed classes or schedule [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":21635,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,11,51,52,53,54,55],"tags":[146,735,1147,147,156,1146],"week":[1136],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/Screenshot-2024-10-03-at-10.07.13.png","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21633"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=21633"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21633\/revisions"}],"predecessor-version":[{"id":21639,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21633\/revisions\/21639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/21635"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=21633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=21633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=21633"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=21633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}