{"id":21761,"date":"2024-10-24T13:12:20","date_gmt":"2024-10-24T13:12:20","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=21761"},"modified":"2024-10-24T13:12:21","modified_gmt":"2024-10-24T13:12:21","slug":"pyp-halloween-celebration-update-friday-november-8th","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/pyp-halloween-celebration-update-friday-november-8th\/","title":{"rendered":"AGGIORNAMENTO Celebrazione di Halloween in PYP - venerd\u00ec 8 novembre"},"content":{"rendered":"<p>I nostri studenti DP sono stati impegnati nell'organizzazione di una giornata speciale per i nostri studenti PYP<strong> <strong>venerd\u00ec 8 novembre<\/strong><\/strong>. Il pomeriggio sar\u00e0 ricco di eventi, giochi e competizioni con un biglietto d'ingresso facoltativo di 5 euro, il cui ricavato sar\u00e0 devoluto all'associazione benefica di loro scelta, <a href=\"https:\/\/www.giocareincorsia.com\/\" target=\"_blank\" rel=\"noopener\">LILT Giocare in Corsia<\/a>. Ulteriori informazioni sono nel poster dell\u2019evento qui sotto. Gli studenti possono portare i soldi il venerd\u00ec mattina e consegnarli direttamente agli organizzatori del DP. <\/p>\n\n\n\n<p>Gli studenti sono invitati a vestirsi in costume per rendere l'esperienza pi\u00f9 emozionante: possono cambiarsi nel pomeriggio dopo la pausa. Gli studenti EYU invece possono venire a scuola indossando il loro costume.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/Halloween-PYP-Poster-724x1024.jpg\" alt=\"\" class=\"wp-image-21732\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/Halloween-PYP-Poster-724x1024.jpg 724w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/Halloween-PYP-Poster-212x300.jpg 212w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/Halloween-PYP-Poster-768x1087.jpg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/Halloween-PYP-Poster-8x12.jpg 8w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/Halloween-PYP-Poster.jpg 841w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Our DP students have been busy organising a special day for our PYP students on Friday, November 8th. The afternoon will be filled with events, games and competitions with an optional 5 Euro entrance fee, with all proceeds going to the charity of their choice, LILT Giocare in Corsia. Please see the poster for additional [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58,1],"tags":[367,474,1164,200,198,645,1165],"week":[1168],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DP-event-poster.png","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21761"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=21761"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21761\/revisions"}],"predecessor-version":[{"id":21764,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21761\/revisions\/21764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/21762"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=21761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=21761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=21761"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=21761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}