{"id":21777,"date":"2024-10-24T14:22:09","date_gmt":"2024-10-24T14:22:09","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=21777"},"modified":"2024-10-24T14:22:09","modified_gmt":"2024-10-24T14:22:09","slug":"myp-1-3-stem-event%ef%bf%bc","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/myp-1-3-stem-event%ef%bf%bc\/","title":{"rendered":"Evento STEM MYP 1-3"},"content":{"rendered":"<p>Siamo contenti di condividere che le ragazze di M1-3 si sono divertite moltissimo partecipando al recente evento STEM di g4g (Greenlight for Girls) e Applied Materials in Europe, dove si sono cimentate in attivit\u00e0 pratiche e laboratori stimolanti incentrati su scienza, tecnologia, ingegneria e matematica. \u00c8 stata una splendida opportunit\u00e0 per loro di esplorare il mondo delle STEM e di entrare in contatto con professionisti del settore.<\/p>\n\n\n\n<p>Prossime opportunit\u00e0 per i ragazzi e le ragazze di M1-3 di partecipare a eventi simili incentrati sulle STEM saranno disponibili nel corso dell'anno. Restate sintonizzati per ulteriori dettagli su come tutti gli studenti possono essere coinvolti!<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-4-1024x681.jpeg\" alt=\"\" class=\"wp-image-21778\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-4-1024x681.jpeg 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-4-300x200.jpeg 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-4-768x511.jpeg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-4-1536x1022.jpeg 1536w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-4-18x12.jpeg 18w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-4-1920x1277.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-27-1024x681.jpeg\" alt=\"\" class=\"wp-image-21779\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-27-1024x681.jpeg 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-27-300x200.jpeg 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-27-768x511.jpeg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-27-1536x1022.jpeg 1536w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-27-18x12.jpeg 18w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-27-1920x1277.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-35-1024x681.jpeg\" alt=\"\" class=\"wp-image-21780\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-35-1024x681.jpeg 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-35-300x200.jpeg 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-35-768x511.jpeg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-35-1536x1022.jpeg 1536w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-35-18x12.jpeg 18w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-35-1920x1277.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>We are excited to share that the M1-3 girls had a fantastic time attending the recent g4g (Greenlight for Girls) &amp; Applied Materials in Europe STEM event, where they engaged in hands-on activities and inspiring workshops focused on science, technology, engineering, and mathematics. It was a wonderful opportunity for them to explore the world of [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":21781,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[11,51,52,53],"tags":[1177,68,1176,1175,182,1004,183],"week":[1168],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/10\/DAY-4-33-scaled.jpeg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21777"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=21777"}],"version-history":[{"count":1,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21777\/revisions"}],"predecessor-version":[{"id":21782,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21777\/revisions\/21782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/21781"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=21777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=21777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=21777"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=21777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}