{"id":21929,"date":"2024-11-14T14:52:52","date_gmt":"2024-11-14T14:52:52","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=21929"},"modified":"2024-11-14T14:52:53","modified_gmt":"2024-11-14T14:52:53","slug":"myp3-myp4-percorso-successo-notturno-presentazione-e-nuova-riunione-online","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/myp3-myp4-pathway-night-success-presentation-and-new-online-meeting\/","title":{"rendered":"Ottimo riscontro per la serata sul percorso MYP3-MYP4: presentazione e nuovo meeting online"},"content":{"rendered":"<p>Desideriamo esprimere il nostro sincero ringraziamento a tutti voi che avete partecipato alla serata di presentazione del percorso M3-M4, rendendo l'evento davvero memorabile. Il vostro entusiasmo, le domande e la dedizione ai percorsi di apprendimento dei vostri figli sono stati evidenti. \u00c8 stato davvero stimolante vedere cos\u00ec tanti genitori e studenti interagire attivamente con i nostri insegnanti, il tutto accompagnato da sorrisi. Ci dispiace per il freddo e il buio che avete dovuto affrontare al rientro.&nbsp;<\/p>\n\n\n\n<p>Nonostante la fredda serata di novembre, avete contribuito a creare un'atmosfera accogliente nella music room e non solo, dove ogni postazione era animata da curiosit\u00e0 ed entusiasmo. La vostra partecipazione ha reso la serata davvero speciale, e siamo felici di aver avuto l'opportunit\u00e0 di condividere con voi il nostro percorso accademico. Vi invitiamo a consultare <a href=\"https:\/\/docs.google.com\/presentation\/d\/11kJXdvxyVLdE6-qDuGmae5zQU9MsgiOHd2cpm4Cweik\/edit?usp=sharing\" target=\"_blank\" rel=\"noopener\">a questo link<\/a> la presentazione condivisa durante l'evento.<\/p>\n\n\n\n<p>Per coloro che hanno perso l'evento in presenza di marted\u00ec scorso, invito i genitori ad un <strong>meeting online sul percorso M3-4 previsto per gioved\u00ec, 28 novembre alle 10:00.<\/strong> Spiegher\u00f2 i punti principali riguardo le materie core ed elettive e potrete farmi delle domande. Vi invito a partecipare alla riunione al seguente link: <a href=\"http:\/\/meet.google.com\/vwk-ywma-pqk\" target=\"_blank\" rel=\"noopener\">meet.google.com\/vwk-ywma-pqk<\/a><\/p>\n\n\n\n<p>Ancora una volta, grazie per aver contribuito al successo della serata di presentazione del percorso. Non vediamo l'ora di proseguire insieme questo viaggio attraverso MYP4 e oltre.&nbsp;<\/p>\n\n\n\n<p>Grazie,&nbsp;<\/p>\n\n\n\n<p>Giles Isbell<\/p>\n\n\n\n<p>Capo di MYPM4-5<\/p>","protected":false},"excerpt":{"rendered":"<p>We would like to extend our sincere gratitude to all of you who joined us for M3-M4 Pathway Night, making it a truly memorable event. Your enthusiasm, questions, and dedication to your children\u2019s learning pathways were evident, and it was inspiring to see so many parents and students actively engaging with our teachers with smiles [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":19636,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[53],"tags":[241,68,14,151,130,1185,153],"week":[1202],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2023\/10\/CMP_2023_09_28_Drone_Andrea_25_social.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21929"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=21929"}],"version-history":[{"count":4,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21929\/revisions"}],"predecessor-version":[{"id":21947,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/21929\/revisions\/21947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/19636"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=21929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=21929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=21929"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=21929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}