{"id":22206,"date":"2024-12-10T14:32:17","date_gmt":"2024-12-10T14:32:17","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=22206"},"modified":"2024-12-12T15:14:41","modified_gmt":"2024-12-12T15:14:41","slug":"pyp-myp-collaboration","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/pyp-myp-collaboration\/","title":{"rendered":"Collaborazione PYP\/MYP"},"content":{"rendered":"<p>La scorsa settimana, gli studenti PYP4 hanno lanciato un entusiasmante progetto inaugurale con Valentino Torre, uno studente MYP5, con l'obiettivo di creare un'opera d'arte originale da inserire nel concorso globale organizzato da <a href=\"https:\/\/www.neversuchinnocence.com\/\" target=\"_blank\" rel=\"noopener\"><em>Never Such Innocence<\/em><\/a>, un'organizzazione che incoraggia i giovani di et\u00e0 compresa tra i 9 e i 18 anni ad usare l'arte come mezzo per riflettere sulla guerra e sui conflitti, e che sta collaborando  con 129 Paesi di tutto il mondo. Valentino, che due anni fa ha ricevuto un premio al concorso internazionale dell'organizzazione creando un filmato accompagnato da poesie e musiche originali, \u00e8 ora <a href=\"https:\/\/www.neversuchinnocence.com\/young-ambassadors\" target=\"_blank\" rel=\"noopener\">ambasciatore italiano dei giovani <\/a>per la loro missione. In collaborazione con Ms Denisse, stanno aiutando a condurre discussioni in merito e a creare opere d'arte che esplorano l'intersezione tra l'arte e l'esplorazione del tema <a href=\"https:\/\/www.neversuchinnocence.com\/2024-25-competition\" target=\"_blank\" rel=\"noopener\">Conversazioni di Conflitto.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Last week, the PYP4 students launched an exciting inaugural project with Valentino Torre, an MYP5 student, with the goal of creating an original art piece to be entered into the global competition organized by Never Such Innocence, an organization that empowers young people ages 9-18 to use art as a means of reflecting on war [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22209,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[11,55,8,57,1],"tags":[],"week":[1266],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/12\/never-such-inn-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22206"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=22206"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22206\/revisions"}],"predecessor-version":[{"id":22208,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22206\/revisions\/22208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/22209"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=22206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=22206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=22206"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=22206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}