{"id":22479,"date":"2025-01-23T15:21:00","date_gmt":"2025-01-23T15:21:00","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=22479"},"modified":"2025-01-23T15:53:54","modified_gmt":"2025-01-23T15:53:54","slug":"pta-event-traditional-chinese-medicine-workshop","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/pta-event-traditional-chinese-medicine-workshop\/","title":{"rendered":"Evento PTA - workshop di Medicina Tradizionale Cinese"},"content":{"rendered":"<p>Il PTA \u00e8 lieto di invitarvi ad un workshop illuminante sulla <strong>medicina tradizionale cinese<\/strong>!<\/p>\n\n\n\n<p>Esplorate le antiche pratiche di guarigione e i rimedi erboristici. Scoprite l'approccio olistico alla salute utilizzato da secoli in Cina.<\/p>\n\n\n\n<p>Questo evento in presenza \u00e8 previsto per <strong>venerd\u00ec, 31 gennaio alle 09:00<\/strong> nel <strong>Campus di H-FARM - edificio MYP<\/strong>, dove potrete immergervi nella saggezza di questo sistema di medicina tradizionale. Non perdete l'occasione di esplorare la ricca storia e i benefici della Medicina Tradizionale Cinese!<\/p>\n\n\n\n<p>Lo spazio \u00e8 limitato a 40 persone. Prenota il tuo posto <a href=\"https:\/\/www.eventbrite.it\/e\/1204708187619?aff=oddtdtcreator\" target=\"_blank\" rel=\"noopener\">a questo linka questo link<\/a>.<\/p>\n\n\n\n<p>A presto!<\/p>\n\n\n\n<p>Il PTA<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1024\" height=\"664\" src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/01\/1-1-1024x664.png\" alt=\"\" class=\"wp-image-22496\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/01\/1-1-1024x664.png 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/01\/1-1-300x194.png 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/01\/1-1-768x498.png 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/01\/1-1-18x12.png 18w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/01\/1-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>The PTA invites you to an enlightening workshop on Traditional Chinese Medicine! Learn about ancient healing practices, herbal remedies. Discover the holistic approach to health that has been used for centuries in China. This in-person event is scheduled for Friday, January 31st at 09:00 AM and it will be held at the H-FARM Campus &#8211; [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":22499,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,11,51,52,53,54,55,8,62,63,64,49,50,56,57,58],"tags":[1338,241,1013,130,149,209,134],"week":[1324],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/01\/SON-covers-venezia-33.png","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22479"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=22479"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22479\/revisions"}],"predecessor-version":[{"id":22498,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22479\/revisions\/22498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/22499"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=22479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=22479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=22479"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=22479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}