{"id":22624,"date":"2025-02-06T15:21:54","date_gmt":"2025-02-06T15:21:54","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=22624"},"modified":"2025-02-06T15:21:59","modified_gmt":"2025-02-06T15:21:59","slug":"h-farm-summer-academy-exclusive-discount","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/h-farm-summer-academy-exclusive-discount\/","title":{"rendered":"H-FARM Summer Academy - Sconto esclusivo!"},"content":{"rendered":"<p>State pensando a un'esperienza estiva dinamica e gratificante che vada oltre il semplice divertimento?<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/courses.h-farm.com\/en?gad_source=1&amp;gclid=CjwKCAiA2JG9BhAuEiwAH_zf3m87AGmalBO6gIxTnPJuFCzXuqtza0iwdl2AgTb8QuPesbpyZrFgFxoCgegQAvD_BwE\" target=\"_blank\" rel=\"noopener\">H-FARM Summer Academy<\/a> accoglie studenti dai 6 ai 19 anni con programmi progettati per ispirare, educare e preparare al futuro.<\/strong><\/p>\n\n\n\n<ul><li><strong>Per gli studenti pi\u00f9 giovani (6-13 anni):<\/strong>&nbsp;Impara, gioca e stimola la tua immaginazione attraverso esperienze pratiche e interattive in cui l'istruzione e il divertimento vanno di pari passo.<\/li><li><strong>Per gli studenti delle scuole superiori (14-19 anni):<\/strong>&nbsp;Sviluppa competenze chiave, esplora le tue passioni e rafforza le tue candidature all'universit\u00e0 partecipando a programmi che sviluppano il pensiero critico, la risoluzione dei problemi e la leadership, preparandoti al contempo per il tuo futuro accademico.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h4 class=\"has-text-align-center\">Siamo entusiasti di offrire&nbsp;<strong>alle famiglie H-IS uno sconto esclusivo del 50% su tutti i programmi:<\/strong><\/h4>\n\n\n\n<ul><li><strong>his-ovn-2025:<\/strong>&nbsp;50% di sconto, valido per tutte le esperienze con pernottamento<\/li><li><strong>his-day-2025:<\/strong>&nbsp;50% di sconto, valido per tutte le esperienze giornaliere<\/li><\/ul>\n\n\n\n<p>Scegliete tra una serie di corsi estivi, tra cui:<\/p>\n\n\n\n<ul><li><strong>H-FARM Startup Bootcamp AI Edition<\/strong><\/li><li><strong>H-FARM Startup Bootcamp Climate Tech Edition<\/strong><\/li><li><strong>Made in Italy Fashion Design Edition<\/strong><\/li><li><strong>Made in Italy Coding &amp; Game Development Edition<\/strong><\/li><li><strong>Scuola di Orientamento Universitario<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center\"><strong>State pensando di iscrivervi a un'universit\u00e0 all'estero per la vostra laurea triennale?<\/strong><\/p>\n\n\n\n<p><br>Sapevate che le esperienze di summer school sono rilevanti e contano ai fini del vostro portfolio&nbsp;<strong>CAS<\/strong>&nbsp;e le vostre candidature all'universit\u00e0 (CV e lettere motivazionali)?&nbsp;<strong>H-FARM Summer Academy<\/strong>&nbsp;offre programmi dinamici in cui gli studenti sviluppano il pensiero critico, la capacit\u00e0 di risolvere problemi, la creativit\u00e0, il lavoro di squadra e le doti di leadership, il tutto mentre esplorano le proprie passioni in un ambiente pratico e coinvolgente.<\/p>\n\n\n\n<p>Indipendentemente dall'et\u00e0, c'\u00e8 un'opportunit\u00e0 per ognuno. All'&nbsp;<strong>H-FARM Summer Academy<\/strong>vi aiutiamo a imparare, crescere e vivere un'estate indimenticabile.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Are you considering a dynamic and enriching summer experience that goes beyond just fun? H-FARM Summer Academy welcomes students aged 6 to 19 with programs designed to inspire, educate, and prepare you for the future. For younger students (6-13 years old):&nbsp;Learn, play, and spark your imagination through hands-on, interactive experiences where education and fun go [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":22626,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,11,51,52,53,54,55,8,62,63,64,49,50,56,57,58],"tags":[807,271,808,811,14,1376,156,404,310],"week":[1363],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-06-at-14.25.21.png","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22624"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=22624"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22624\/revisions"}],"predecessor-version":[{"id":22627,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/22624\/revisions\/22627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/22626"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=22624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=22624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=22624"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=22624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}