{"id":23184,"date":"2025-04-17T14:50:43","date_gmt":"2025-04-17T14:50:43","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=23184"},"modified":"2025-04-18T06:50:09","modified_gmt":"2025-04-18T06:50:09","slug":"upcoming-daily-educational-visits-myp3","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/upcoming-daily-educational-visits-myp3\/","title":{"rendered":"Prossime visite didattiche giornaliere MYP3"},"content":{"rendered":"<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-1-color\">Venezia Guggenheim: Esplorando i Capolavori Moderni \u2013 12 Maggio<\/mark><\/strong><\/p>\n\n\n\n<p>nostri studenti di M3 visiteranno la <strong>Collezione Peggy Guggenheim<\/strong> a Venezia per una giornata immersi nell\u2019arte moderna! Esploreranno l\u2019impressionante collezione di capolavori del <strong>XX secolo<\/strong>, con opere di artisti come Picasso, Kandinsky e Pollock. Questa visita offrir\u00e0 agli studenti un\u2019opportunit\u00e0 unica per confrontarsi con l\u2019arte contemporanea e approfondire la comprensione dei movimenti artistici che hanno plasmato il mondo moderno.<\/p>\n\n\n\n<ul><li><strong>Data: 12 maggio<\/strong><\/li><li><strong>Ore 9:00 \u2013 Ritrovo al trattore<\/strong><\/li><li>Visita guidata alla Collezione Guggenheim<\/li><li>Pranzo al sacco e merenda<\/li><li>14:00 Trip back&nbsp; with boat&nbsp;<\/li><li>Ore 15:30 \u2013 Rientro in Campus<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-1-color\">Gita a Ravenna: Alla scoperta dell\u2019eredit\u00e0 di Dante \u2013 29 Maggio<\/mark><\/strong><\/p>\n\n\n\n<p>Gli studenti si recheranno a <strong>Ravenna<\/strong> per una giornata ricca di esplorazione culturale. Al <strong>mattino<\/strong>, visiteranno i <strong>siti Patrimonio dell\u2019Umanit\u00e0 UNESCO<\/strong>, inclusa <strong>San Vitale<\/strong>, <strong>Sant\u2019Apollinare Nuovo<\/strong>, e il <strong>Museo Arcivescovile<\/strong>approfondendo la conoscenza dei meravigliosi mosaici e dell\u2019architettura paleocristiana di Ravenna.<\/p>\n\n\n\n<p>Nel <strong>pomeriggio<\/strong>, il focus si sposter\u00e0 su <strong>Dante Alighieri<\/strong>, con una passeggiata guidata attraverso i luoghi legati agli ultimi anni del poeta in esilio, concludendo con la visita alla sua tomba e al <strong>Museo Dante<\/strong>Un\u2019esperienza interdisciplinare che unisce storia, letteratura e arte.<\/p>\n\n\n\n<ul><li><strong>Data: 29 maggio<\/strong><\/li><li><strong>Ore 7:00 \u2013 Ritrovo al trattore<\/strong><\/li><li>Visita guidata dei siti storici<\/li><li>Pranzo al sacco e merende<\/li><li>Tour dantesco<\/li><li>Rientro in Campus nel tardo pomeriggio<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p class=\"has-text-align-center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-1-color\">Trento MUSE: Dal Banco di Scuola al Mondo della Scienza \u2013 3 Giugno<\/mark><\/strong><\/p>\n\n\n\n<p>A giugno, i nostri studenti M3 andranno al <strong>MUSE \u2013 Museo delle Scienze<\/strong> di Trento per una giornata entusiasmante all\u2019insegna della scienza! Questo museo scientifico di fama internazionale, progettato dall\u2019architetto Renzo Piano, offre esposizioni interattive incentrate su <strong>natura, sostenibilit\u00e0, scienza del clima<\/strong>, e <strong>innovazione<\/strong>.<\/p>\n\n\n\n<ul><li><strong>Data: 3 giugno<\/strong><\/li><li><strong>Ore 7:40 \u2013 Ritrovo al trattore<\/strong><\/li><li>Visita guidata al MUSE<\/li><li>Attivit\u00e0 laboratoriale<\/li><li>Pranzo al sacco e merende<\/li><li>Tour del museo<\/li><li>Attivit\u00e0 laboratoriale<\/li><li>Ore 19:00 \u2013 Rientro in Campus&nbsp;<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Venice Guggenheim: Exploring Modern Masterpieces, May 12 Our M3 students are heading to the Peggy Guggenheim Collection in Venice for a day immersed in modern art! They will explore the museum\u2019s impressive collection of 20th-century masterpieces, featuring works by artists such as Picasso, Kandinsky, and Pollock. This visit will offer students a unique opportunity to [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":23186,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[53],"tags":[1252,1525,1309,1524,209,182,156,1310,329,590,748],"week":[1500],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/04\/SON-covers-venezia-73.png","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23184"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=23184"}],"version-history":[{"count":3,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23184\/revisions"}],"predecessor-version":[{"id":23218,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23184\/revisions\/23218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/23186"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=23184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=23184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=23184"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=23184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}