{"id":23668,"date":"2025-08-28T16:44:49","date_gmt":"2025-08-28T16:44:49","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=23668"},"modified":"2025-08-28T16:44:50","modified_gmt":"2025-08-28T16:44:50","slug":"a-message-from-the-head-of-pyp-mr-anthony","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/a-message-from-the-head-of-pyp-mr-anthony\/","title":{"rendered":"Un messaggio dall\u2019Head of PYP, Mr Anthony"},"content":{"rendered":"<p>Cari genitori e tutori,<\/p>\n\n\n\n<p>All\u2019inizio del mio secondo anno come Head of PYP qui a H-FARM International School, desidero ringraziarvi per la calorosa accoglienza e il forte sostegno che mi avete dimostrato durante il mio primo anno. \u00c8 stato stimolante vedere i nostri studenti crescere in tanti ambiti \u2014 non solo dal punto di vista accademico, ma anche nelle loro amicizie, nella creativit\u00e0 e nel senso di responsabilit\u00e0 come membri della nostra comunit\u00e0.<\/p>\n\n\n\n<p>Quest\u2019anno, la nostra attenzione condivisa continua a concentrarsi sulle Sei Dimensioni del Successo, che ci guidano nel supportare ogni aspetto dello sviluppo dei bambini. Vogliamo che i nostri studenti crescano emotivamente, sviluppando fiducia, resilienza e felicit\u00e0 in ci\u00f2 che sono. Vogliamo che vivano il successo nell\u2019apprendimento, attraverso esperienze di ricerca significative, stimolanti e gioiose. Con il successo nella comunit\u00e0, imparano a collaborare, prendersi cura degli altri e contribuire positivamente al mondo che li circonda. Il successo linguistico rimane centrale nella nostra scuola: aiuta i bambini a esprimersi con sicurezza in inglese, ma anche a comprendere l\u2019importanza della propria lingua madre nel costruire connessioni tra culture diverse. La preparazione accademica si costruisce su solide basi di alfabetizzazione, calcolo e capacit\u00e0 di pensiero critico, che li preparano ad affrontare con sicurezza l\u2019apprendimento futuro. Infine, il successo sociale viene coltivato in ogni interazione in classe e nei momenti di gioco, dove gli studenti imparano inclusione, empatia e la gioia di far parte di una comunit\u00e0 internazionale.<\/p>\n\n\n\n<p>Uno degli aspetti pi\u00f9 gratificanti del mio primo anno \u00e8 stato constatare quanto possa essere potente la collaborazione tra casa e scuola. \u00c8 insieme che creiamo le condizioni perch\u00e9 i nostri studenti possano prosperare. Vi incoraggio ancora una volta a restare vicini all\u2019apprendimento dei vostri figli, fare domande, condividere esperienze e celebrare i loro progressi.<\/p>\n\n\n\n<p>Sono entusiasta di continuare questo percorso con voi e attendo con gioia un altro anno ricco di crescita, creativit\u00e0 e successo in tutte le sue dimensioni.<\/p>\n\n\n\n<p>Un caro saluto,<br>Anthony Hamblin<br>Head of PYP<\/p>","protected":false},"excerpt":{"rendered":"<p>Dear Parents and Guardians, As I begin my second year as Head of PYP at H-FARM International School, I would like to thank you for the warm welcome and strong support you shared throughout my first year. It was inspiring to watch our students flourish across so many areas \u2014 not only in academics, but [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21359,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58],"tags":[1095,1034,1072,236,567],"week":[1633],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2024\/08\/H-IS_HAMBLIN_ANTHONY-JOSEPH_2024_7_social.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23668"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=23668"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23668\/revisions"}],"predecessor-version":[{"id":25941,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23668\/revisions\/25941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/21359"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=23668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=23668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=23668"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=23668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}