{"id":23715,"date":"2025-08-28T16:46:20","date_gmt":"2025-08-28T16:46:20","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=23715"},"modified":"2025-09-02T06:20:32","modified_gmt":"2025-09-02T06:20:32","slug":"the-story-of-us","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/the-story-of-us\/","title":{"rendered":"The Story Of Us"},"content":{"rendered":"<p>Care famiglie<\/p>\n\n\n\n<p>Siamo lieti di condividere con voi l' <strong><a href=\"https:\/\/www.figma.com\/proto\/uwRrFXr9atuc0HpoLgeBJv\/The-story-of-us---Venezia?page-id=01&amp;node-id=798-361&amp;p=f&amp;viewport=-455460.09&amp;t=EIa92RO3PxuZpKtm-1&amp;scaling=min-zoom&amp;content-scaling=fixed&amp;starting-point-node-id=798361\" target=\"_blank\" rel=\"noopener\">Story of Us<\/a><\/strong>, un documento che raccoglie i momenti pi\u00f9 significativi dello scorso anno scolastico. Al suo interno troverete un riepilogo delle molte attivit\u00e0, dei progetti e degli eventi che hanno dato forma alla nostra comunit\u00e0, insieme ai traguardi e ai successi raggiunti dai nostri studenti.<\/p>\n\n\n\n<p>Non si tratta soltanto di un resoconto: \u00e8 una vera e propria celebrazione dell\u2019apprendimento, della creativit\u00e0 e dell\u2019impegno che hanno reso lo scorso anno cos\u00ec speciale. Dai risultati accademici alle performance artistiche, dalle competizioni sportive alle iniziative di comunit\u00e0, ogni pagina riflette l\u2019energia, la passione e la resilienza dei nostri studenti e del nostro staff.<\/p>\n\n\n\n<p>Al centro di questo percorso ci sono le nostre Sei Dimensioni del Successo. Sono loro a guidarci nel prenderci cura dello studente nella sua interezza, ricordandoci che la crescita non si misura solo nei voti, ma anche nella fiducia, nell\u2019empatia, nella curiosit\u00e0 e nella resilienza che i nostri ragazzi sviluppano lungo il cammino.<\/p>\n\n\n\n<p>Vi invitiamo a sfogliare questo documento non solo come testimonianza di quanto \u00e8 stato realizzato, ma anche come fonte di ispirazione mentre guardiamo con entusiasmo al nuovo anno scolastico.<\/p>\n\n\n\n<p>Grazie per il vostro continuo supporto.<\/p>\n\n\n\n<div class=\"wp-container-1 is-content-justification-center wp-block-buttons\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.figma.com\/proto\/uwRrFXr9atuc0HpoLgeBJv\/The-story-of-us---Venezia?page-id=01&amp;node-id=798-361&amp;p=f&amp;viewport=-455460.09&amp;t=EIa92RO3PxuZpKtm-1&amp;scaling=min-zoom&amp;content-scaling=fixed&amp;starting-point-node-id=798361\" target=\"_blank\" rel=\"noreferrer noopener\">Story Of Us<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dear Families We are pleased to share with you the Story of Us, a document that brings together the highlights of the past school year. Inside, you will find a recap of the many activities, projects, and events that shaped our community, along with the milestones and successes our students have achieved. This is more [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16778,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,11,51,52,53,54,55,8,62,63,64,49,50,56,57,58],"tags":[],"week":[1633],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2022\/09\/CMP_2021_06_16_DronateCampus_01_social.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23715"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=23715"}],"version-history":[{"count":5,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23715\/revisions"}],"predecessor-version":[{"id":23749,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/23715\/revisions\/23749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/16778"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=23715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=23715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=23715"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=23715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}