{"id":24395,"date":"2025-11-13T17:25:42","date_gmt":"2025-11-13T17:25:42","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=24395"},"modified":"2025-11-13T17:25:44","modified_gmt":"2025-11-13T17:25:44","slug":"now-open-marine-biology-expedition-to-the-maldives-april-2026","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/now-open-marine-biology-expedition-to-the-maldives-april-2026\/","title":{"rendered":"Iscrizioni aperte ora: Spedizione di Biologia Marina alle Maldive \u2013 Aprile 2026"},"content":{"rendered":"<p>Care Famiglie e cari Studenti,<\/p>\n\n\n\n<p>siamo entusiasti di annunciare che <strong>sono ufficialmente aperte le iscrizioni<\/strong> per la data di Aprile 2026 della  <a href=\"https:\/\/drive.google.com\/file\/d\/10SZb2l2ndayTuIdTrD-yQ3bteH5-3n-H\/view?usp=drive_link\" target=\"_blank\" rel=\"noopener\"><strong>spedizione scientifica alle Maldive per il progetto di Biologia Marina<\/strong><\/a>, organizzata in collaborazione con l\u2019 <strong>Universit\u00e0 di Padova.<\/strong>.<\/p>\n\n\n\n<p><strong>\ud83c\udf34 Destinazione:<\/strong> Isola di Feridhoo, Maldive<br><strong>\ud83d\uddd3\ufe0f Durata:<\/strong> 8 giorni \/ 7 notti<br><strong>\ud83d\udd2c Focus:<\/strong> Biologia marina \u2013 attivit\u00e0 sul campo, osservazione e ricerca<br><strong>\ud83d\udcb6 Costo stimato:<\/strong> \u20ac2.800 \u2013 \u20ac3.200<\/p>\n\n\n\n<p><strong>Guarda il video di presentazione:<\/strong><a href=\"https:\/\/youtu.be\/GgfW1UVJDWQ?si=r-ElABYwacEnWWq2\" target=\"_blank\" rel=\"noopener\"> <\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Coral restoration in the Maldives\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/GgfW1UVJDWQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>I posti sono limitati e gli studenti saranno selezionati dal <strong>Dipartimento di Scienze<\/strong> tra coloro che si registreranno. Sono previste <strong>due partenze separate<\/strong> previste per aprile 2026.<\/p>\n\n\n\n<p>Questa esperienza educativa immersiva prevede workshop e attivit\u00e0 incentrate su <strong>biologia marina, biodiversit\u00e0, ecologia, gestione delle risorse naturali e sostenibilit\u00e0<\/strong>. Gli studenti interessati alla biologia marina potranno anche raccogliere dati utili per il proprio <strong>Extended Essay (EE)<\/strong> oppure <strong>Internal Assessment (IA)<\/strong>.<br>Inoltre, la partecipazione a questa uscita sar\u00e0 valida come <strong>esperienza CAS<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3><strong>Attivit\u00e0 Didattiche:<\/strong><\/h3>\n\n\n\n<ul><li><strong>Scuba Diving:<br><\/strong>Ogni studente effettuer\u00e0 un\u2019immersione subacquea di 50 minuti, che comprender\u00e0 l'osservazione della barriera corallina e dei vivai, la pulizia dei coralli e la raccolta di dati (es. misurazione degli steli).<br><em>Immersioni aggiuntive potranno essere organizzate nel tempo libero con un costo extra.<br><\/em><\/li><li><strong>Snorkelling:<br><\/strong> Due sessioni guidate sono incluse:<ul><li>Una sessione in piccolo gruppo (3 studenti per guida)<\/li><li>Una sessione di gruppo su un\u2019isola deserta con due guide (inclusa escursione in barca)<br><em>Una sessione di snorkeling notturno potr\u00e0 essere offerta in base alle condizioni del mare.<br><\/em><\/li><\/ul><\/li><li><strong>Alloggi:<br><\/strong>Gli studenti alloggeranno presso <a href=\"https:\/\/www.villarosamaldives.com\/eng\/villa-rosa-maldives-guest-house\" target=\"_blank\" rel=\"noopener\"><strong>Villa Rosa Guest House<\/strong><\/a>, un resort a 5 stelle situato sull\u2019isola di Feridhoo, che offre:<\/li><\/ul>\n\n\n\n<ul><li>Tre pasti casalinghi al giorno<\/li><li>Cinque camere con letti queen-size, aria condizionata, bagno privato e giardino<\/li><li>Pulizia giornaliera della stanza e cambio asciugamani ogni due giorni<\/li><li>A soli 10 minuti a piedi dalla Bikini Beach<\/li><\/ul>\n\n\n\n<p>Il gruppo sar\u00e0 supervisionato dal personale di <strong>Coral Restoration<\/strong> e <strong>da docenti della scuola<\/strong> per garantire la sicurezza.<\/p>\n\n\n\n<ul><li><strong>Divisione in gruppi e abbigliamento:<\/strong><strong><br><\/strong>I gruppi saranno organizzati cercando un equilibrio di genere. Si ricorda che \u00e8 richiesto un abbigliamento rispettoso delle <strong>usanze locali<\/strong>. I costumi in stile occidentale sono consentiti solo nel resort e nelle spiagge autorizzate.<br><\/li><li><strong>Viaggio e Costi:<\/strong><strong><br><\/strong>Il <strong>costo totale stimato<\/strong>, comprensivo di voli e tasse, \u00e8 di <strong>\u20ac2,800-\u20ac3,200<\/strong> a studente.<br><em>Il prezzo finale potr\u00e0 variare in base alla disponibilit\u00e0 dei voli.<\/em><\/li><\/ul>\n\n\n\n<h3 class=\"has-text-align-center\"><strong>Sei interessato? Registrati qui (senza impegno): <a href=\"https:\/\/forms.gle\/A6TrTQujTjMzPs6Q9\" target=\"_blank\" rel=\"noopener\">https:\/\/forms.gle\/A6TrTQujTjMzPs6Q9<\/a><\/strong><\/h3>\n\n\n\n<p>Dopo il processo di selezione, riceverete maggiori dettagli sulle date del viaggio e su come confermare la partecipazione tramite caparra.<\/p>\n\n\n\n<p>Non perdete questa straordinaria opportunit\u00e0 di esplorare le Maldive attraverso un viaggio scientifico unico e indimenticabile!<\/p>\n\n\n\n<p>Cordiali saluti,<br>Student Office<\/p>","protected":false},"excerpt":{"rendered":"<p>Dear Families and Students, We are thrilled to announce that registration is now open for the upcoming April 2026 Marine Biology Field Trip to the Maldives, organised in collaboration with the University of Padua. \ud83c\udf34 Destination: Feridhoo Island, Maldives\ud83d\uddd3\ufe0f Duration: 8 days \/ 7 nights\ud83d\udd2c Focus: Marine biology \u2013 hands-on fieldwork, observation, and research\ud83d\udcb6 Estimated [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":23192,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[1630,59,54,55],"tags":[271,241,1501,1507,209,156,173],"week":[1799],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/04\/dion-tavenier-h-Qb-9H6Big-unsplash-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24395"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=24395"}],"version-history":[{"count":1,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24395\/revisions"}],"predecessor-version":[{"id":24396,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24395\/revisions\/24396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/23192"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=24395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=24395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=24395"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=24395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}