{"id":24513,"date":"2025-11-27T15:02:13","date_gmt":"2025-11-27T15:02:13","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=24513"},"modified":"2025-11-27T15:02:16","modified_gmt":"2025-11-27T15:02:16","slug":"world-childrens-day-my-day-my-rights-in-pyp","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/world-childrens-day-my-day-my-rights-in-pyp\/","title":{"rendered":"Giornata Mondiale dei Diritti dell\u2019Infanzia My Day, My Rights\u201d in PYP"},"content":{"rendered":"<p>La settimana scorsa la nostra scuola ha celebrato con orgoglio la <strong>Giornata Mondiale dei Diritti dell\u2019Infanzia<\/strong>: un momento importante in cui la nostra comunit\u00e0 si \u00e8 unita per riconoscere e promuovere i diritti, le voci e il benessere dei bambini di tutto il mondo. \u00c8 stata una giornata dedicata alla gentilezza, all\u2019equit\u00e0 e alla consapevolezza che i pensieri e le azioni dei nostri studenti hanno valore.<\/p>\n\n\n\n<p>Il tema di quest\u2019anno, <strong>\u201cMy Day, My Rights\u201d<\/strong> , ha invitato gli studenti a riflettere sui diritti per loro pi\u00f9 significativi. Per onorare questo tema, abbiamo realizzato un bellissimo murales collaborativo nell\u2019area Welcome del PYP. Ogni bambino ha contribuito con un\u2019impronta della propria mano dipinta, simbolo della sua voce unica e del suo posto nella nostra comunit\u00e0. Su ciascuna impronta, gli studenti hanno scritto un diritto dell\u2019infanzia in cui credono, dal diritto di giocare e imparare al diritto di sentirsi al sicuro e accuditi.<\/p>\n\n\n\n<p>Molte famiglie hanno dedicato del tempo a casa per parlare dei diritti che i loro figli considerano importanti, e questo sostegno ha aiutato gli studenti a sentirsi sicuri e consapevoli nel contribuire al nostro murales.<\/p>\n\n\n\n<p>Siamo orgogliosi delle conversazioni significative, della creativit\u00e0 e della consapevolezza nate da questa celebrazione. Ora il murales \u00e8 esposto all\u2019esterno dell\u2019Outlook, come un colorato promemoria dell\u2019importanza dei diritti dei bambini e dei messaggi potenti condivisi dai nostri studenti.<\/p>\n\n\n\n<figure class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery aligncenter has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"461\" data-id=\"24519\"  src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057497-1024x461.jpeg\" alt=\"\" class=\"wp-image-24519\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057497-1024x461.jpeg 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057497-300x135.jpeg 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057497-768x346.jpeg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057497-1536x691.jpeg 1536w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057497-18x8.jpeg 18w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057497.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"462\" height=\"1024\" data-id=\"24517\"  src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057496-462x1024.jpeg\" alt=\"\" class=\"wp-image-24517\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057496-462x1024.jpeg 462w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057496-135x300.jpeg 135w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057496-693x1536.jpeg 693w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057496-5x12.jpeg 5w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057496.jpeg 721w\" sizes=\"(max-width: 462px) 100vw, 462px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"461\" data-id=\"24518\"  src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057498-1024x461.jpeg\" alt=\"\" class=\"wp-image-24518\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057498-1024x461.jpeg 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057498-300x135.jpeg 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057498-768x346.jpeg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057498-1536x691.jpeg 1536w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057498-18x8.jpeg 18w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057498.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"461\" data-id=\"24516\"  src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057499-1024x461.jpeg\" alt=\"\" class=\"wp-image-24516\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057499-1024x461.jpeg 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057499-300x135.jpeg 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057499-768x346.jpeg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057499-1536x691.jpeg 1536w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057499-18x8.jpeg 18w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057499.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"461\" data-id=\"24520\"  src=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057500-1-1024x461.jpeg\" alt=\"\" class=\"wp-image-24520\" srcset=\"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057500-1-1024x461.jpeg 1024w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057500-1-300x135.jpeg 300w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057500-1-768x346.jpeg 768w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057500-1-1536x691.jpeg 1536w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057500-1-18x8.jpeg 18w, https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057500-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>Last week, our school proudly celebrated World Children\u2019s Rights Day: a meaningful moment when our community came together to recognise and promote the rights, voices, and well-being of children everywhere. It was a day dedicated to kindness, fairness, and empowering students to understand that their thoughts and actions matter. This year\u2019s theme, \u201cMy Day, My [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24515,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58],"tags":[920,1826,1827,1825],"week":[1822],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/11\/1000057500.jpeg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24513"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=24513"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24513\/revisions"}],"predecessor-version":[{"id":24521,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24513\/revisions\/24521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/24515"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=24513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=24513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=24513"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=24513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}