{"id":24671,"date":"2025-12-11T15:14:49","date_gmt":"2025-12-11T15:14:49","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=24671"},"modified":"2025-12-11T15:14:51","modified_gmt":"2025-12-11T15:14:51","slug":"venissa-restaurant-event-in-school-for-myp5","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/venissa-restaurant-event-in-school-for-myp5\/","title":{"rendered":"Ristorante Venissa per evento MYP5 a scuola"},"content":{"rendered":"<h6>Siamo entusiasti di condividere una collaborazione unica con <strong>Venissa<\/strong>, il ristorante stellato Michelin sull\u2019isola di Mazzorbo. Nell\u2019ambito di questo progetto, i nostri studenti di MYP5 realizzeranno un\u2019\u201cesperienza\u201d originale, pensata per rispondere alle reali esigenze di Venissa, mettendo in pratica capacit\u00e0 imprenditoriali, creative e di business in una sfida autentica e reale.<\/h6>\n\n\n\n<h6>Gli studenti presenteranno le loro proposte durante una visita speciale alla Tenuta di Venissa il 3 febbraio, davanti a una commissione composta dagli chef e dal management del ristorante, insieme ad alcuni dei nostri insegnanti: una vera esperienza professionale di pitching in un contesto d\u2019eccezione.<\/h6>\n\n\n\n<h6>Per rendere la sfida ancora pi\u00f9 entusiasmante, il contest prevede premi straordinari:<\/h6>\n\n\n\n<p><strong>1\u00b0 premio: <\/strong>pranzo stellato Michelin da Venissa + una giornata intera di shadowing con il loro team professionale.<\/p>\n\n\n\n<p><strong>2\u00b0 e 3\u00b0 premio:<\/strong> pranzo presso l\u2019Osteria Contemporanea di Venissa.<\/p>\n\n\n\n<p>E oltre ai premi, c\u2019\u00e8 qualcosa di ancora pi\u00f9 stimolante: il concept vincitore potrebbe essere realizzato da Venissa, con crediti ufficiali attribuiti agli studenti, offrendo loro la rara opportunit\u00e0 di vedere le proprie idee diventare realt\u00e0.<\/p>\n\n\n\n<h6>Non vediamo l\u2019ora di vedere brillare la loro creativit\u00e0!<\/h6>","protected":false},"excerpt":{"rendered":"<p>We are thrilled to share a unique collaboration with Venissa, the Michelin-starred restaurant on Mazzorbo island. As part of this project, our MYP5 students will create an original \u201cexperience\u201d tailored to Venissa\u2019s real needs, putting their entrepreneurship, creativity, and business skills into action in a truly authentic, real-world challenge. Students will present their proposals during [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":24672,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[1630,458,55],"tags":[644,1858,1859,1860,209,1857],"week":[1853],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2025\/12\/d_copertina-venissa.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24671"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=24671"}],"version-history":[{"count":1,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24671\/revisions"}],"predecessor-version":[{"id":24673,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24671\/revisions\/24673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/24672"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=24671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=24671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=24671"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=24671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}