{"id":24949,"date":"2026-01-22T14:52:41","date_gmt":"2026-01-22T14:52:41","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=24949"},"modified":"2026-01-22T14:52:44","modified_gmt":"2026-01-22T14:52:44","slug":"pyp-pick-up-procedures","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/pyp-pick-up-procedures\/","title":{"rendered":"Procedure di uscita PYP"},"content":{"rendered":"<p>Cari genitori, vi ricordiamo le <strong>procedure di uscita<\/strong> , disponibili anche nel <a href=\"https:\/\/docs.google.com\/document\/d\/1f0ZeIDGsNdn5ibfTQAXMhYVAXQAbRQMjJNv7VXx8CLw\/edit?tab=t.0\" target=\"_blank\" rel=\"noopener\">Parent Handbook PYP.<\/a><br><\/p>\n\n\n\n<p>Uscita del pomeriggio: <strong>alle 15:15, all\u2019esterno del Welcome Centre.<\/strong><\/p>\n\n\n\n<ul><li>Tutti gli studenti saranno accompagnati dagli insegnanti nell\u2019area coperta fuori dal Welcome Centre.<\/li><li>I genitori sono pregati di attendere dal lato del parcheggio, dietro le grandi piante.<\/li><li>Gli insegnanti consegneranno gli studenti uno alla volta, da adulto ad adulto.<\/li><li>Vi chiediamo di assicurarvi che la segreteria sia informata con anticipo di eventuali <a href=\"https:\/\/docs.google.com\/document\/d\/1f0ZeIDGsNdn5ibfTQAXMhYVAXQAbRQMjJNv7VXx8CLw\/edit?tab=t.0#heading=h.8cwp06dgmwrg\" target=\"_blank\" rel=\"noopener\">accordi alternativi<\/a> per l\u2019uscita dei vostri bambini (ad esempio: un altro genitore delegato, una festa di compleanno, ecc.).<\/li><\/ul>\n\n\n\n<p>Vi chiediamo di NON:<\/p>\n\n\n\n<ul><li>Attendere davanti al cancello PYP<\/li><li>Entrare nell\u2019edificio a fine giornata per ritirare vostro\/a figlio\/a<\/li><li>Tentare di ritirare vostro\/a figlio\/a in un punto diverso: la consegna avverr\u00e0 solo presso le piante fuori dal Welcome Centre<\/li><li>Portare vostro\/a figlio\/a via senza aver prima preso contatto con l\u2019insegnante accompagnatore.<\/li><\/ul>\n\n\n\n<p>Vi preghiamo inoltre di condividere queste informazioni con tutti i membri della famiglia e le persone coinvolte nel ritiro (nonni, babysitter, autisti, ecc.).\nGrazie per la collaborazione.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dear parents, a kind reminder of our pick up procedures which can be found in the PYP Parent Handbook. Afternoon pick-up: at 3:15 PM outside the Welcome Centre. All students will be escorted to the covered area outside the Welcome Centre Parents are asked to wait on the parking lot side of the large plants [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24951,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,62,63,64,49,50,56,57,58],"tags":[305,1912,1913,438,1911],"week":[1893],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2026\/01\/pick-up-procedures.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24949"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=24949"}],"version-history":[{"count":2,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24949\/revisions"}],"predecessor-version":[{"id":24952,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/24949\/revisions\/24952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/24951"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=24949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=24949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=24949"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=24949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}