{"id":25012,"date":"2026-02-05T15:24:36","date_gmt":"2026-02-05T15:24:36","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=25012"},"modified":"2026-02-05T15:24:37","modified_gmt":"2026-02-05T15:24:37","slug":"pyp3-educational-visit-clay-workshop-2","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/pyp3-educational-visit-clay-workshop-2\/","title":{"rendered":"PYP3 visita didattica - workshop con l\u2019argilla"},"content":{"rendered":"<p>Cari genitori PYP3,<\/p>\n\n\n\n<p>Questa \u00e8 la nostra prossima uscita didattica! Vi invitiamo a leggere attentamente tutte le informazioni qui sotto e a contattarci in caso di domande. Tutte le visite confermate sono sempre disponibili anche nella sezione \u201cSchool Trips\u201d dell\u2019app H-ello.<\/p>\n\n\n\n<p>Grazie a tutti e cordiali saluti,<br>Y3 team<\/p>\n\n\n\n<p><em>Dettagli:<\/em><\/p>\n\n\n\n<ul><li>Quando:<strong><a href=\"When: Thursday, February 13th\"> <\/a>marted\u00ec 14 aprile (Y3C) e mercoled\u00ec 15 aprile (Y3L)<\/strong><\/li><li>Dove: <strong>a scuola<\/strong><\/li><li>Cosa: <strong>workshop con l\u2019argilla<\/strong><\/li><li>Unit\u00e0 di indagine <strong>Dove siamo nello spazio e nel tempo<\/strong>: siamo entusiasti di annunciare che ad aprile i nostri studenti Year 3 parteciperanno a un coinvolgente laboratorio di argilla all'interno della scuola, condotto dall'azienda Paci Terracotte. Questa esperienza si collegher\u00e0 direttamente alla nostra unit Dove siamo nello spazio  nel tempo, all\u2019interno della quale stiamo esplorando le tracce del passato e il modo in cui queste ci aiutano a comprendere le civilt\u00e0 antiche. <strong>Il nostro caso di studio \u00e8 Pompei,<\/strong> un esempio straordinario di come la vita quotidiana sia stata preservata grazie alla cenere vulcanica. Dagli oggetti domestici alle ceramiche e alle piastrelle decorative, i manufatti in argilla rinvenuti a Pompei ci offrono preziosi indizi sulla cultura, le credenze e le abitudini quotidiane delle persone di un tempo. Durante il laboratorio, gli studenti diventeranno giovani archeologi e artisti, utilizzando l\u2019argilla per ricreare reperti storici e immaginare le storie che questi oggetti potrebbero raccontare. Lavorare con l\u2019argilla non solo rende la storia viva e concreta, ma stimola anche la creativit\u00e0, rafforza le abilit\u00e0 motorie fini e supporta lo sviluppo sensoriale. \u00c8 un materiale calmante ed espressivo che invita alla curiosit\u00e0 e alla riflessione.<\/li><\/ul>\n\n\n\n<p><em>Logistica:<\/em><\/p>\n\n\n\n<ul><li>questi workshop si terranno a scuola durante l'orario scolastico<\/li><li>Cosa indossare: gli studenti devono venire vestiti con <strong>abiti vecchi e scuri.<\/strong> Anche forniremo loro dei grembiuli, lavorare con l'argilla pu\u00f2 essere complicato e i vestiti potrebbero sporcarsi.<\/li><\/ul>\n\n\n\n<p><em>Cosa fare se:<\/em><\/p>\n\n\n\n<ul><li>Mio figlio non pu\u00f2 partecipare: che si tratti di un'assenza programmata o di un\u2019assenza per malattia, vi preghiamo di informarci appena possibile. Nota: la visita didattica \u00e8 a tutti gli effetti una lezione e fa parte del programma didattico della scuola. Per questo motivo ci aspettiamo che tutti gli studenti partecipino.<\/li><\/ul>\n\n\n\n<p><em>Pagamento e conferma<\/em>:<\/p>\n\n\n\n<ul><li>Le visite didattiche giornaliere sono incluse nel pagamento \u201c2025-26 daily trips\u201d quindi non \u00e8 necessario un pagamento aggiuntivo per questa gita.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Dear PYP3 Parents This is our next educational visit! Please read all of the information below and please let us know if you have any questions. Please also note that all confirmed visits are always available also in the &#8220;School Trips&#8221; section of the H-ello app. Thank you and kind regards,The Y3 Team Details: When: [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25026,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[8,56],"tags":[1380,174,477,1381,173,134],"week":[1922],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2026\/02\/clay-pompei.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25012"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=25012"}],"version-history":[{"count":3,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25012\/revisions"}],"predecessor-version":[{"id":25025,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25012\/revisions\/25025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/25026"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=25012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=25012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=25012"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=25012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}