{"id":25408,"date":"2026-03-26T14:33:17","date_gmt":"2026-03-26T14:33:17","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=25408"},"modified":"2026-03-26T14:33:18","modified_gmt":"2026-03-26T14:33:18","slug":"la-mia-gita-di-un-giorno-a-verona-1-aprile","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/myp4-daily-trip-to-verona-april-1st\/","title":{"rendered":"Gita giornaliera MYP4 a Verona - 1 aprile"},"content":{"rendered":"<p>Cari genitori MYP4,<\/p>\n\n\n\n<p>I nostri studenti prenderanno parte a un\u2019esperienza di apprendimento strutturata e di grande valore accademico a Verona, citt\u00e0 di straordinario patrimonio culturale e letterario, strettamente legata all'opera di Shakespeare <em>Romeo e Giulietta<\/em>.<\/p>\n\n\n\n<p>Durante la visita, gli studenti parteciperanno a un tour teatrale guidato attraverso alcuni dei principali luoghi storici della citt\u00e0. Guidati da attori professionisti, alcune scene selezionate dell\u2019opera di Shakespeare saranno interpretate in lingua inglese, offrendo agli studenti l\u2019opportunit\u00e0 di analizzare il testo all\u2019interno di un contesto performativo e storico. Questo approccio favorir\u00e0 una comprensione pi\u00f9 profonda dello sviluppo dei personaggi, dei temi centrali, come conflitto, identit\u00e0 e riconciliazione, e dell\u2019uso del linguaggio come strumento di espressione e interpretazione.<\/p>\n\n\n\n<p>L\u2019esperienza proseguir\u00e0 presso il Teatro Satiro con un laboratorio strutturato dedicato al teatro e alla lingua. Sotto la guida di professionisti del settore, gli studenti esploreranno elementi della performance come voce, movimento e presenza scenica. Attraverso attivit\u00e0 collaborative, applicheranno le proprie capacit\u00e0 interpretative a estratti selezionati, rafforzando sia le competenze di analisi sia la sicurezza nella comunicazione orale.<\/p>\n\n\n\n<p>Questa esperienza \u00e8 pensata per collegare l\u2019analisi letteraria alla pratica, permettendo agli studenti di confrontarsi in modo critico con il testo e di sviluppare competenze fondamentali come comunicazione, collaborazione ed espressione personale. L\u2019attivit\u00e0 mira inoltre a promuovere la consapevolezza culturale e una maggiore comprensione del teatro come strumento attraverso cui la letteratura pu\u00f2 essere esplorata e interpretata.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>QUANDO: mercoled\u00ec 1 aprile<\/strong><\/p>\n\n\n\n<p><strong>Programma della giornata:<\/strong><strong><br><\/strong><strong><br><\/strong>08:30 - Partenza dal trattore rosso in direzione Verona<br>Divisione in 2 gruppi:<br>Gruppo 1:\n10:30 \u2013 12:00 Visita guidata di Verona con performance in maschera in inglese tratte da <em>Romeo e Giulietta<\/em><em><br><\/em><em>Gruppo 2:\n10:30 \u2013 12:00 Workshop presso il Teatro Satiro <\/em><em><br><\/em><em>Dalle 12:00 alle 13:30 i gruppi si alterneranno per partecipare all\u2019attivit\u00e0 non svolta nella prima parte della giornata.<\/em><em><br><\/em>13:30 \u2013 14:30 Pranzo al sacco nei pressi del Teatro Satiro<br>14:30 \u2013 16:15 Rientro a H-FARM Campus<\/p>\n\n\n\n<p><strong>Cosa portare:<\/strong><\/p>\n\n\n\n<p>Quaderno e penna<br>Borraccia d'acqua<br>Giacca anti pioggia e ombrello&nbsp;<\/p>\n\n\n\n<p><strong>Dress code (obbligatorio)<\/strong><\/p>\n\n\n\n<p>Gli studenti sono tenuti a indossare la <strong>divisa scolastica ufficiale<\/strong>, obbligatoria per la partecipazione alla visita.<\/p>\n\n\n\n<p>Gli studenti sono ambasciatori della scuola e sono pertanto tenuti a mantenere elevati standard di comportamento, responsabilit\u00e0 e professionalit\u00e0 durante l\u2019intera esperienza.<\/p>\n\n\n\n<p><strong>Rispetto delle istituzioni ospitanti<\/strong><\/p>\n\n\n\n<p>Il rispetto del dress code \u00e8 obbligatorio e il mancato rispetto pu\u00f2 comportare l\u2019esclusione dall\u2019attivit\u00e0. Durante tutta la visita, gli studenti sono tenuti a comportarsi responsabilmente, comunicare con rispetto e mantenere un atteggiamento adeguato all\u2019ambiente museale. Gli studenti rappresentano la scuola in maniera positiva e devono mostrare gratitudine verso il personale e i curatori che condividono con loro il proprio tempo, competenze e spazio.<\/p>\n\n\n\n<p><strong>Staff accompagnatore<br><\/strong><br>In questo viaggio giornaliero, gli studenti saranno accompagnati dalla Sig.ra Hamilton, dalla Sig.ra Mattiuzzo, dalla Sig.ra Khorsand, dalla Sig.ra Bottrill, dal Sig. Cordeiro, dal Sig. Molinari.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Questa uscita giornaliera \u00e8 inclusa nel pagamento delle <strong>\u201cgite giornaliere 2025\u201326\u201d<\/strong>pertanto non \u00e8 previsto alcun costo aggiuntivo. Poich\u00e9 le gite giornaliere fanno parte del programma accademico, la partecipazione \u00e8 obbligatoria. In caso di assenze programmate, vi chiediamo gentilmente di registrarle tramite lo strumento di gestione delle presenze su <strong>Managebac<\/strong>.<\/p>\n\n\n\n<p>Grazie per il vostro continuo supporto nel garantire ai nostri studenti esperienze di apprendimento significative e connesse al mondo reale.<\/p>\n\n\n\n<p>Cordiali Saluti,<br><strong>Ufficio Studenti MYP<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Dear MYP4 Parents, Our students will take part in a structured and academically enriching learning experience in Verona, a city of significant cultural and literary heritage, closely associated with Shakespeare\u2019s Romeo and Juliet. During the visit, students will engage in a guided theatrical tour through key historical locations in the city. Led by professional actors, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":25409,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[1630,54],"tags":[1993,1992,209,1438,156,933,1181],"week":[1983],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2026\/03\/Juliethouse-exterior.webp","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25408"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=25408"}],"version-history":[{"count":5,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25408\/revisions"}],"predecessor-version":[{"id":25438,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25408\/revisions\/25438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/25409"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=25408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=25408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=25408"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=25408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}