{"id":25642,"date":"2026-05-04T08:43:35","date_gmt":"2026-05-04T08:43:35","guid":{"rendered":"https:\/\/www.schoolnews.h-farm.com\/?p=25642"},"modified":"2026-05-07T14:12:29","modified_gmt":"2026-05-07T14:12:29","slug":"yearbook-purchase-your-copy","status":"publish","type":"post","link":"https:\/\/www.schoolnews.h-farm.com\/it\/yearbook-purchase-your-copy\/","title":{"rendered":"Annuario \u2013 acquista la tua copia!"},"content":{"rendered":"<p>Cari genitori,<\/p>\n\n\n\n<p>Siamo entusiasti di annunciare che il nuovo Annuario Scolastico 2025-2026 sar\u00e0 presto disponibile!<\/p>\n\n\n\n<p>Con l'avvicinarsi della fine dell'anno scolastico, l\u2019annuario rappresenta un modo speciale per raccogliere e celebrare i ricordi, i traguardi e i momenti pi\u00f9 significativi che hanno caratterizzato questi mesi. Dai momenti in classe agli eventi scolastici, \u00e8 un ricordo prezioso pensato per essere sfogliato negli anni a venire.<br>Anche questa edizione mantiene le caratteristiche tanto apprezzate dalla nostra comunit\u00e0: un formato grande, una copertina rigida di alta qualit\u00e0 e una ricca selezione di fotografie che raccontano al meglio la storia dell\u2019anno.<\/p>\n\n\n\n<p><strong>Prezzo Early Bird: \u20ac36<\/strong><\/p>\n\n\n\n<p>Modalit\u00e0 di acquisto:<\/p>\n\n\n\n<ul><li>Accedete alla piattaforma scolastica tramite <a href=\"https:\/\/www.h-is.com\/application\/\" target=\"_blank\" rel=\"noreferrer noopener\">questo link<\/a><\/li><li>Scegliete \u201cattivit\u00e0 extra\u201d, il pulsante quadrato sotto \u201ciscrizione\u201d. Assicuratevi che l'anno accademico sia 2025\/26<\/li><li>Clicca su \u201c25-26 YEARBOOK \u2013 ANNUARIO 25-26\u201d e completa il pagamento<\/li><\/ul>\n\n\n\n<p><strong>Scadenza prevendite: 14 maggio<\/strong><br>Vi invitiamo ad effettuare l\u2019ordine entro questa data. Dopo la scadenza, eventuali ristampe saranno effettuate solo al raggiungimento di un numero minimo di copie richieste, al <strong>prezzo intero di 40 \u20ac.<\/strong><\/p>\n\n\n\n<p><strong>Consegna:<\/strong><br>I yearbook verranno distribuiti a fine maggio \/ inizio giugno.<br>Per tutti gli studenti di DP2, l'annuario pu\u00f2 essere ritirato durante la Cerimonia di Diploma.<br>Non perdere l'occasione di conservare un ricordo duraturo di quest'anno scolastico!<\/p>","protected":false},"excerpt":{"rendered":"<p>Dear Parents, We are excited to announce that the New School Yearbook 2025-2026 will soon be available! As the school year draws to a close, our Yearbook offers a wonderful way to capture and celebrate the memories, achievements and special moments that have defined this year. From classroom highlights to school events, it is a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[6,59,60,11,51,52,53,54,55,8,62,63,64,49,50,56,57,58],"tags":[378],"week":[2025],"jetpack_featured_media_url":"https:\/\/www.schoolnews.h-farm.com\/wp-content\/uploads\/2026\/04\/yearbook-grafica-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25642"}],"collection":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/comments?post=25642"}],"version-history":[{"count":6,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25642\/revisions"}],"predecessor-version":[{"id":25728,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/posts\/25642\/revisions\/25728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media\/25643"}],"wp:attachment":[{"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/media?parent=25642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/categories?post=25642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/tags?post=25642"},{"taxonomy":"week","embeddable":true,"href":"https:\/\/www.schoolnews.h-farm.com\/it\/wp-json\/wp\/v2\/week?post=25642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}